{"id":217217,"date":"2018-02-22T17:59:54","date_gmt":"2018-02-22T16:59:54","guid":{"rendered":"http:\/\/www.radioluna.it\/news\/?p=217217"},"modified":"2018-02-23T04:56:16","modified_gmt":"2018-02-23T03:56:16","slug":"asl-latina-casati-nomina-il-nuovo-direttore-sanitario-aziendale","status":"publish","type":"post","link":"https:\/\/www.radioluna.it\/news\/2018\/02\/asl-latina-casati-nomina-il-nuovo-direttore-sanitario-aziendale\/","title":{"rendered":"Asl Latina, Casati nomina il nuovo direttore sanitario aziendale"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p style=\"text-align: justify;\"><strong>LATINA<\/strong> &#8211; E&#8217; Giuseppe Visconti, 62 anni, il nuovo direttore sanitario aziendale della Asl di Latina. Lo ha nominato il direttore generale Giorgio Casati con delibera pubblicata sull&#8217;albo pretorio on line. Il professionista,\u00a0 specializzato in Igiene e Medicina Preventiva e del Lavoro, e gi\u00e0 direttore di presidio e poi direttore sanitario aziendale della Fondazione Tor Vergata, oltre che professore a contratto del Policlinico di Tor Vergata, entrer\u00e0 in servizio il 1 marzo prossimo e sar\u00e0 legato all&#8217;azienda pontina per tre anni.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>LATINA &#8211; E&#8217; Giuseppe Visconti, 62 anni, il nuovo direttore sanitario aziendale della Asl di Latina. Lo ha nominato il direttore generale Giorgio Casati con delibera pubblicata sull&#8217;albo pretorio on line. Il professionista,\u00a0 specializzato in Igiene e Medicina Preventiva e del Lavoro, e gi\u00e0 direttore di presidio e poi direttore sanitario aziendale della Fondazione Tor [&hellip;]<\/p>\n","protected":false},"author":62,"featured_media":217219,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[7],"tags":[],"class_list":["post-217217","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cronaca"],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/217217","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/users\/62"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/comments?post=217217"}],"version-history":[{"count":0,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/217217\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/media\/217219"}],"wp:attachment":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/media?parent=217217"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/categories?post=217217"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/tags?post=217217"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}