{"id":217530,"date":"2018-02-27T08:15:08","date_gmt":"2018-02-27T07:15:08","guid":{"rendered":"http:\/\/www.radioluna.it\/news\/?p=217530"},"modified":"2018-02-28T21:41:22","modified_gmt":"2018-02-28T20:41:22","slug":"regalo-dalla-semprevisa","status":"publish","type":"post","link":"https:\/\/www.radioluna.it\/news\/2018\/02\/regalo-dalla-semprevisa\/","title":{"rendered":"Regalo dalla Semprevisa"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p style=\"text-align: justify;\"><strong>LATINA<\/strong> &#8211; La consideriamo la parte poetica di una giornata un po&#8217; speciale, quella della neve e del freddo siberiano che la provincia di Latina \u00e8 poco abituata a vivere. Davvero spettacolare la foto della Semprevisa scattata da Francesca Santinelli e diffusa dalla guida naturalistica Saverio D&#8217;Ottavi. Ieri ha fatto rapidamente il giro dei social nei gruppi pontini ricevendo centinaia di commenti e condivisioni.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>LATINA &#8211; La consideriamo la parte poetica di una giornata un po&#8217; speciale, quella della neve e del freddo siberiano che la provincia di Latina \u00e8 poco abituata a vivere. Davvero spettacolare la foto della Semprevisa scattata da Francesca Santinelli e diffusa dalla guida naturalistica Saverio D&#8217;Ottavi. Ieri ha fatto rapidamente il giro dei social [&hellip;]<\/p>\n","protected":false},"author":62,"featured_media":217531,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[7],"tags":[],"class_list":["post-217530","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cronaca"],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/217530","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/users\/62"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/comments?post=217530"}],"version-history":[{"count":0,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/217530\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/media\/217531"}],"wp:attachment":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/media?parent=217530"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/categories?post=217530"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/tags?post=217530"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}