{"id":270773,"date":"2020-07-11T11:21:30","date_gmt":"2020-07-11T09:21:30","guid":{"rendered":"https:\/\/www.radioluna.it\/news\/?p=270773"},"modified":"2020-07-14T19:25:51","modified_gmt":"2020-07-14T17:25:51","slug":"larbitro-gavillucci-a-latina-ecco-chi-e-luomo-nero","status":"publish","type":"post","link":"https:\/\/www.radioluna.it\/news\/2020\/07\/larbitro-gavillucci-a-latina-ecco-chi-e-luomo-nero\/","title":{"rendered":"L&#8217;arbitro Gavillucci a Latina: &#8220;Ecco chi \u00e8 L&#8217;Uomo Nero&#8221;"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p style=\"text-align: justify;\"><strong>LATINA &#8211; A Latina, <\/strong>nella citt\u00e0 che lo ha visto crescere anche professionalmente, orgogliosa prima per il suo ingresso nella Can A, e poi al suo fianco nella battaglia seguita all&#8217;esclusione, <strong>Claudio Gavillucci<\/strong> ha presentato a Latina, <strong>nell&#8217;Arena San Francesco in Via dei Cappuccini,<\/strong> <strong>l&#8217;Uomo nero &#8211; le verit\u00e0 di un arbitro scomodo (ed Chiarelettere)<\/strong>, il libro scritto con <strong>A<span dir=\"ltr\">ntonietta Ferrante<\/span>,\u00a0<\/strong><span dir=\"ltr\"><strong>Manuela D&#8217;Alessandro<\/strong> <\/span>che con documenti inediti racconta un pezzo di storia del calcio italiano.\u00a0 L&#8217;invito era arrivato dall&#8217;organizzatore, <strong>Enzo De Amicis<\/strong> che lo ha accolto per il primo appuntamento della rassegna con<strong> il giornalista<\/strong> <strong>Pasquale Cangianiello e l&#8217;avvocato Gianluca Ciotti che ha assistito Gavillucci.<\/strong><\/p>\n<p style=\"text-align: justify;\">&#8220;L&#8217;uomo nero &#8211; ha spiegato Gavillucci &#8211; E&#8217; un titolo nato prima del libro stesso: l&#8217;uomo nero \u00e8 l&#8217;arbitro, ma anche purtroppo il giocatore di colore che troppe volte viene preso di mira nei nostri stadi. Parliamo di razzismo e di mancanza di trasparenza&#8221;, spiega.<\/p>\n<p>Qui Gavillucci intervistato per noi da <strong>Domenico Ippoliti<\/strong><\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-270773-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2020\/07\/gavillucci.mp3?_=1\" \/><a href=\"https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2020\/07\/gavillucci.mp3\">https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2020\/07\/gavillucci.mp3<\/a><\/audio>\n<div id=\"radio-2525450338\" class=\"radio-dopo-il-contenuto radio-entity-placement\"><a href=\"https:\/\/concessionari-suzuki.it\/bodema\/\" aria-label=\"Bodema 1200&#215;600 banner Suzuki_AX\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2025\/05\/Bodema-1200x600-banner-Suzuki_AX.jpg\" alt=\"\"  srcset=\"https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2025\/05\/Bodema-1200x600-banner-Suzuki_AX.jpg 1200w, https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2025\/05\/Bodema-1200x600-banner-Suzuki_AX-768x384.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" width=\"800\" height=\"300\"   \/><\/a><\/div>","protected":false},"excerpt":{"rendered":"<p>LATINA &#8211; A Latina, nella citt\u00e0 che lo ha visto crescere anche professionalmente, orgogliosa prima per il suo ingresso nella Can A, e poi al suo fianco nella battaglia seguita all&#8217;esclusione, Claudio Gavillucci ha presentato a Latina, nell&#8217;Arena San Francesco in Via dei Cappuccini, l&#8217;Uomo nero &#8211; le verit\u00e0 di un arbitro scomodo (ed Chiarelettere), [&hellip;]<\/p>\n","protected":false},"author":62,"featured_media":270774,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[2310,17],"tags":[],"class_list":["post-270773","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-audio","category-sport"],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/270773","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/users\/62"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/comments?post=270773"}],"version-history":[{"count":0,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/270773\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/media\/270774"}],"wp:attachment":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/media?parent=270773"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/categories?post=270773"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/tags?post=270773"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}