{"id":270810,"date":"2020-07-11T13:33:48","date_gmt":"2020-07-11T11:33:48","guid":{"rendered":"https:\/\/www.radioluna.it\/news\/?p=270810"},"modified":"2020-07-11T13:33:48","modified_gmt":"2020-07-11T11:33:48","slug":"a-gaeta-bruciano-20-ettari-di-bosco-e-macchia-mediterranea","status":"publish","type":"post","link":"https:\/\/www.radioluna.it\/news\/2020\/07\/a-gaeta-bruciano-20-ettari-di-bosco-e-macchia-mediterranea\/","title":{"rendered":"A Gaeta bruciano 20 ettari di bosco e macchia mediterranea"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p><!-- Embedded with Magic Embeds - https:\/\/magicembeds.com --><\/p>\n<div class=\"wef-measure\" style=\"max-width: 1000px;\"><\/div>\n<div class=\"fb-video\" data-href=\"https:\/\/www.facebook.com\/vigilfuocolatina\/videos\/989033141520747\/\" data-allowfullscreen=\"false\" data-autoplay=\"false\" data-width=\"1000\" data-show-text=\"false\" data-show-captions=\"true\"><\/div>\n<p style=\"text-align: justify;\"><strong>GAETA &#8211;<\/strong> \u00a0Venti ettari di vegetazione sono andati distrutti in un incendio divampato nel pomeriggio di venerd\u00ec a Gaeta in localit\u00e0 Monte Dragone. E&#8217; il primo di queste proporzioni in questo avvio d&#8217;estate. le operazioni di spegnimento da parte dei Vigili del fuoco sono terminate solo nelle prime ore di questa mattina quando due elicotteri si sono levati in volo e hanno portato a termine il lavoro avviato ieri da una squadra a terra e da quattro velivoli, due due Canadair dei vigili del fuoco e due elicotteri antincendio della Regione Lazio. In fumo bosco e macchia mediterranea.<\/p>\n<div id=\"radio-3057785060\" class=\"radio-dopo-il-contenuto radio-entity-placement\"><a href=\"https:\/\/concessionari-suzuki.it\/bodema\/\" aria-label=\"Bodema 1200&#215;600 banner Suzuki_AX\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2025\/05\/Bodema-1200x600-banner-Suzuki_AX.jpg\" alt=\"\"  srcset=\"https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2025\/05\/Bodema-1200x600-banner-Suzuki_AX.jpg 1200w, https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2025\/05\/Bodema-1200x600-banner-Suzuki_AX-768x384.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" width=\"800\" height=\"300\"   \/><\/a><\/div>","protected":false},"excerpt":{"rendered":"<p>GAETA &#8211; \u00a0Venti ettari di vegetazione sono andati distrutti in un incendio divampato nel pomeriggio di venerd\u00ec a Gaeta in localit\u00e0 Monte Dragone. E&#8217; il primo di queste proporzioni in questo avvio d&#8217;estate. le operazioni di spegnimento da parte dei Vigili del fuoco sono terminate solo nelle prime ore di questa mattina quando due elicotteri [&hellip;]<\/p>\n","protected":false},"author":62,"featured_media":270811,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[7],"tags":[2879,164,538,23,2154,365],"class_list":["post-270810","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cronaca","tag-elicotteri","tag-gaeta","tag-incendio","tag-latina","tag-notizie-di-latina","tag-vigili-del-fuoco"],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/270810","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/users\/62"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/comments?post=270810"}],"version-history":[{"count":0,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/270810\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/media\/270811"}],"wp:attachment":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/media?parent=270810"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/categories?post=270810"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/tags?post=270810"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}