{"id":272148,"date":"2020-07-28T19:26:27","date_gmt":"2020-07-28T17:26:27","guid":{"rendered":"https:\/\/www.radioluna.it\/news\/?p=272148"},"modified":"2020-07-29T19:23:47","modified_gmt":"2020-07-29T17:23:47","slug":"latina-accogliera-allex-rossi-sud-57-migranti-sbarcati-a-lampedusa","status":"publish","type":"post","link":"https:\/\/www.radioluna.it\/news\/2020\/07\/latina-accogliera-allex-rossi-sud-57-migranti-sbarcati-a-lampedusa\/","title":{"rendered":"Latina accoglier\u00e0 all&#8217;ex Rossi Sud 57 migranti sbarcati a Lampedusa"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p style=\"text-align: justify;\"><strong>LATINA<\/strong> &#8211; <strong>Arriveranno a Latina nella notte 57 migranti sbarcati nelle scorse ore a Lampedusa.<\/strong> Latina, infatti, come altri Comuni italiani e del Lazio, \u00e8 stata chiamata a contribuire alla gestione dell&#8217;emergenza. E&#8217; stato il battesimo per <strong>il neo prefetto di Latina, Maurizio Falco<\/strong>. Le decisioni circa la dislocazione dei migranti per la maggior parte tunisini in fuga dal proprio Paese sono state prese in accordo con la Asl per stabilire le misure di sicurezza sanitarie necessarie.<\/p>\n<p style=\"text-align: justify;\">In una conferenza stampa che si \u00e8 tenuta oggi pomeriggio nella Sala Cambellotti con lo scopo di informare la popolazione, il Prefetto ha spiegato che <strong>\u00e8 stato scelto il sito ex Rossi Sud sulla via del Monti Lepini messo a disposizione dalla Provincia<\/strong> che ne \u00e8 proprietaria. Domani mattina saranno sottoposti a tampone tutti gli ospiti e i risultati degli esami sono attesi per il pomeriggio.\u00a0 E&#8217; questa l&#8217;operazione preliminare da effettuare. Poi si decider\u00e0 sulla gestione dei singoli, a seconda dello stato di salute e dello status giuridico. &#8220;Se sono cittadini tunisini come dichiarano, saranno tutti avviati alle procedure di espulsione&#8221;, ha spiegato Falco che ha ringraziato tutte le autorit\u00e0 cittadine e provinciali per la collaborazione e la capacit\u00e0 di rapida gestione dell&#8217;emergenza.<\/p>\n<p><strong>ASCOLTA<\/strong><\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-272148-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2020\/07\/prefetto-falco-migranti.mp3?_=1\" \/><a href=\"https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2020\/07\/prefetto-falco-migranti.mp3\">https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2020\/07\/prefetto-falco-migranti.mp3<\/a><\/audio>\n<p style=\"text-align: justify;\"><strong> Il sindaco di Latina Damiano Coletta<\/strong> ha spiegato che le necessit\u00e0 davanti alle quali ci si trova oggi sono diverse da quelle di ieri. Il modello di accoglienza fino ad ora adottato prevedeva infatti la dispersione sul territorio per una migliore distribuzione dei migranti, mentre l\u2019emergenza Covid richiede che siano raccolti in un unico luogo, perch\u00e9 non abbiano contatti con l&#8217;esterno prima che siano accertate le condizioni di salute.<\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-272148-2\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2020\/07\/coletta-migranti.mp3?_=2\" \/><a href=\"https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2020\/07\/coletta-migranti.mp3\">https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2020\/07\/coletta-migranti.mp3<\/a><\/audio>\n<p style=\"text-align: justify;\"><strong>I TAMPONI<\/strong> &#8211; <strong>Alla Asl spetter\u00e0 effettuare i tamponi<\/strong> e si comincer\u00e0 domattina facendo slittare di qualche ore quelli previsti su 300 persone appartenenti alla comunit\u00e0 indiana residente a Bella Farnia. Controlli necessari per evitare l&#8217;insorgere di nuovi focolai dovuti ai rientri e alla difficolt\u00e0 di rispettare le misure di distanziamento nelle abitazioni in cui i cittadini indiani spesso vivono numerosi. &#8220;Ringraziamo le forze dell&#8217;ordine che sci aiutano nelle attivit\u00e0 quotidiane e i rappresentanti della comunit\u00e0 indiana che stanno collaborando attivamente&#8221;, ha detto <strong>Antonio Sabatucci direttore del Dipartimento di Prevenzione della Asl di Latina.<\/strong><\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-272148-3\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2020\/07\/sabatucci.mp3?_=3\" \/><a href=\"https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2020\/07\/sabatucci.mp3\">https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2020\/07\/sabatucci.mp3<\/a><\/audio>\n<p style=\"text-align: justify;\"><strong>Sotto il coordinamento della Questura saranno tutte le forze dell&#8217;ordine, polizia di stato, carabinieri e guardia di finanza,<\/strong> a garantire la sicurezza all&#8217;interno della ex Rossi Sud, sorvegliando che nessuno si allontani come ha spiegato il <strong>Questore di Latina Michele Spina<\/strong><\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-272148-4\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2020\/07\/questore-migranti.mp3?_=4\" \/><a href=\"https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2020\/07\/questore-migranti.mp3\">https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2020\/07\/questore-migranti.mp3<\/a><\/audio>\n<p>&nbsp;<\/p>\n<div id=\"radio-666662137\" class=\"radio-dopo-il-contenuto radio-entity-placement\"><a href=\"https:\/\/concessionari-suzuki.it\/bodema\/\" aria-label=\"Bodema 1200&#215;600 banner Suzuki_AX\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2025\/05\/Bodema-1200x600-banner-Suzuki_AX.jpg\" alt=\"\"  srcset=\"https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2025\/05\/Bodema-1200x600-banner-Suzuki_AX.jpg 1200w, https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2025\/05\/Bodema-1200x600-banner-Suzuki_AX-768x384.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" width=\"800\" height=\"300\"   \/><\/a><\/div>","protected":false},"excerpt":{"rendered":"<p>LATINA &#8211; Arriveranno a Latina nella notte 57 migranti sbarcati nelle scorse ore a Lampedusa. Latina, infatti, come altri Comuni italiani e del Lazio, \u00e8 stata chiamata a contribuire alla gestione dell&#8217;emergenza. E&#8217; stato il battesimo per il neo prefetto di Latina, Maurizio Falco. Le decisioni circa la dislocazione dei migranti per la maggior parte [&hellip;]<\/p>\n","protected":false},"author":62,"featured_media":272152,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[2310,7],"tags":[],"class_list":["post-272148","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-audio","category-cronaca"],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/272148","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/users\/62"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/comments?post=272148"}],"version-history":[{"count":0,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/272148\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/media\/272152"}],"wp:attachment":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/media?parent=272148"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/categories?post=272148"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/tags?post=272148"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}