{"id":275478,"date":"2020-09-28T10:40:25","date_gmt":"2020-09-28T08:40:25","guid":{"rendered":"https:\/\/www.radioluna.it\/news\/?p=275478"},"modified":"2020-09-29T03:28:52","modified_gmt":"2020-09-29T01:28:52","slug":"la-catena-rosa-della-prevenzione-consegnata-ad-aprilia-parte-ottobre-rosa","status":"publish","type":"post","link":"https:\/\/www.radioluna.it\/news\/2020\/09\/la-catena-rosa-della-prevenzione-consegnata-ad-aprilia-parte-ottobre-rosa\/","title":{"rendered":"La Catena Rosa della prevenzione consegnata ad Aprilia: parte Ottobre Rosa"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p style=\"text-align: justify;\"><strong> <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-275502\" src=\"https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2020\/09\/NASTRO-ROSA-2020.jpg\" alt=\"\" width=\"960\" height=\"720\" srcset=\"https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2020\/09\/NASTRO-ROSA-2020.jpg 960w, https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2020\/09\/NASTRO-ROSA-2020-768x576.jpg 768w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/>LATINA &#8211; <\/strong>Comincia Ottobre Rosa il mese della prevenzione del tumore al seno, iniziativa promossa nell&#8217;ambito della Campagna Mondiale Nastro Rosa in cui sar\u00e0 possibile eseguire la mammografia gratuitamente nelle strutture pubbliche, non solo per chi \u00e8 gi\u00e0 in fascia di screening, ma anche per le donne pi\u00f9 giovani di et\u00e0 compresa tra i 45 anni e i 50.<\/p>\n<p style=\"text-align: justify;\">La <strong>Catena Rosa<\/strong>, che da qualche anno unisce idealmente i Comuni della provincia di Latina nell\u2019impegno su questo fronte, quest\u2019anno \u00e8 stata consegnata al Comune di <strong>Aprilia <\/strong>nelle mani del primo cittadino <strong>Antonio Terra<\/strong> dalla sindaca di <strong>Sermoneta, Giuseppina Giovannoli<\/strong> alla presenza del <strong>Prefetto Maurizio Falco<\/strong>: \u00a0una catena di lana rosa, lavorata, partita anni fa da Roccagorga da una idea dell\u2019allora Sindaca Carla Amici, e che ha gi\u00e0 raggiunto Minturno, Gaeta, Terracina e Sermoneta e che, in futuro, continuer\u00e0 a girare negli altri Comuni della provincia di Latina per richiamare l&#8217;attenzione di tutti sull&#8217;importanza della lotta contro il cancro al seno.<\/p>\n<p style=\"text-align: justify;\">A presentare le iniziative e il rinnovato sodalizio tra istituzioni e mondo del volontariato, sono state sabato scorso <strong>LILT, ASL, Breast Unit e Universit\u00e0 Sapienza Polo Pontino<\/strong>, in una conferenza moderata dalla giornalista Mariassunta D\u2019Alessio. I relatori, la\u00a0 prof.ssa Antonella Calogero, il prof. Fabio Ricci, il dott. Luigi Rossi, hanno posto l&#8217;accento sui numeri, le nuove cure, le prospettive della ricerca, sulla qualit\u00e0 della vita e la certezza che si pu\u00f2 ridurre ancora la mortalit\u00e0 per cancro al seno fino alla sua sconfitta.<\/p>\n<p style=\"text-align: justify;\">&#8220;Le Breast Unit, nate in tutta Italia hanno fatto aumentare del 20% la sopravvivenza delle donne colpite dal tumore al seno. Ricordarlo \u00e8 dunque un imperativo etico e una precisa scelta culturale fondata su principi di giustizia ed uguaglianza e criteri di qualit\u00e0 e umanit\u00e0, integrando forze e competenze. Questo mese \u00e8 un appuntamento con la speranza&#8221;, ha voluto sottolineare <strong>Fabio Ricci Direttore clinico della Creast Unit del Goretti<\/strong> ospite questa mattina ai nostri microfoni<\/p>\n<p>ASCOLTA<\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-275478-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2020\/09\/ricci-per-sito.mp3?_=1\" \/><a href=\"https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2020\/09\/ricci-per-sito.mp3\">https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2020\/09\/ricci-per-sito.mp3<\/a><\/audio>\n<div id=\"radio-3515593968\" class=\"radio-dopo-il-contenuto radio-entity-placement\"><a href=\"https:\/\/concessionari-suzuki.it\/bodema\/\" aria-label=\"Bodema 1200&#215;600 banner Suzuki_AX\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2025\/05\/Bodema-1200x600-banner-Suzuki_AX.jpg\" alt=\"\"  srcset=\"https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2025\/05\/Bodema-1200x600-banner-Suzuki_AX.jpg 1200w, https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2025\/05\/Bodema-1200x600-banner-Suzuki_AX-768x384.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" width=\"800\" height=\"300\"   \/><\/a><\/div>","protected":false},"excerpt":{"rendered":"<p>LATINA &#8211; Comincia Ottobre Rosa il mese della prevenzione del tumore al seno, iniziativa promossa nell&#8217;ambito della Campagna Mondiale Nastro Rosa in cui sar\u00e0 possibile eseguire la mammografia gratuitamente nelle strutture pubbliche, non solo per chi \u00e8 gi\u00e0 in fascia di screening, ma anche per le donne pi\u00f9 giovani di et\u00e0 compresa tra i 45 [&hellip;]<\/p>\n","protected":false},"author":62,"featured_media":275501,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[735,2310],"tags":[69,2509,2784,23,313,3085,2154,3081,3082,3084,3083,376],"class_list":["post-275478","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-attualita","category-audio","tag-aprilia","tag-asl-latina","tag-fabio-ricci","tag-latina","tag-lilt","tag-nastro-rosa","tag-notizie-di-latina","tag-ottobre-rosa","tag-prevenzione","tag-sapienza-polo-pontino","tag-screenig","tag-sermoneta"],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/275478","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/users\/62"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/comments?post=275478"}],"version-history":[{"count":0,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/275478\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/media\/275501"}],"wp:attachment":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/media?parent=275478"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/categories?post=275478"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/tags?post=275478"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}