{"id":277239,"date":"2020-10-24T10:14:04","date_gmt":"2020-10-24T08:14:04","guid":{"rendered":"https:\/\/www.radioluna.it\/news\/?p=277239"},"modified":"2020-10-24T12:02:09","modified_gmt":"2020-10-24T10:02:09","slug":"asl-latina-da-oggi-geolocalizziamo-i-casi-per-intervenire-in-maniera-mirata-anche-con-i-controlli","status":"publish","type":"post","link":"https:\/\/www.radioluna.it\/news\/2020\/10\/asl-latina-da-oggi-geolocalizziamo-i-casi-per-intervenire-in-maniera-mirata-anche-con-i-controlli\/","title":{"rendered":"Asl Latina: &#8220;Da oggi geolocalizziamo i casi per intervenire in maniera mirata anche con i controlli&#8221;"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p style=\"text-align: justify;\"><strong>LATINA &#8211;<\/strong>\u00a0<strong>Geolocalizzare i casi di Covid-19,<\/strong> ovvero prendere la cartina geografica della provincia e la mappa delle strade cittadine di ogni Comune e verificare dove sono emersi i nuovi positivi. In questo modo, durante il lockdown a Fondi venne fuori che intere strade pullulavano di contagiati e in misura minore \u00e8 accaduto anche a Formia, a settembre con il primo focolaio della coda estiva.<\/p>\n<p style=\"text-align: justify;\">&#8220;E&#8217; arrivato il momento di riprendere in mano questo strumento per capire meglio che cosa succede, perch\u00e9 e come intervenire, conoscendo in maniera pi\u00f9 capillare la diffusione del virus <strong>Sars Cov-2 sul nostro territorio, Comune per Comune. <\/strong>Anche i controlli potranno cos\u00ec essere\u00a0 pi\u00f9 mirati&#8221;. Lo ha detto <strong>il direttore generale della Asl Giorgio Casati<\/strong> spiegando che stavolta si proceder\u00e0 ad una geolocalizzazione anche per fasce di et\u00e0.<\/p>\n<p><strong>ascolta<\/strong><\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-277239-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2020\/10\/casati-geolocalizzazione.mp3?_=1\" \/><a href=\"https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2020\/10\/casati-geolocalizzazione.mp3\">https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2020\/10\/casati-geolocalizzazione.mp3<\/a><\/audio>\n<p style=\"text-align: justify;\">La decisione \u00e8 arrivata dopo l&#8217;escalation dei casi in provincia di Latina, che ha sta riguardando in particolare i Comuni dell&#8217;area nord della provincia: <strong>Latina, Cisterna e Aprilia.<\/strong> Nel comune capoluogo i positivi attivi (al 23 ottobre) erano 431, l&#8217;8% dei quali ricoverato in ospedale. Divisi pi\u00f9 o meno equamente tra Aprilia e Cisterna ci sono poi, altri 500 positivi attivi, di cui 50 (il 10%) hanno richiesto cure ospedaliere con ricovero. Il totale dei contagiati\u00a0 nei tre comuni &#8211; due dei quali sono tra i pi\u00f9 popolosi del Lazio &#8211;\u00a0 rappresenta circa i due terzi degli attuali positivi attivi sull&#8217;intero territorio provinciale (1589).<\/p>\n<p>&nbsp;<\/p>\n<div id=\"radio-804415772\" class=\"radio-dopo-il-contenuto radio-entity-placement\"><a href=\"https:\/\/concessionari-suzuki.it\/bodema\/\" aria-label=\"Bodema 1200&#215;600 banner Suzuki_AX\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2025\/05\/Bodema-1200x600-banner-Suzuki_AX.jpg\" alt=\"\"  srcset=\"https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2025\/05\/Bodema-1200x600-banner-Suzuki_AX.jpg 1200w, https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2025\/05\/Bodema-1200x600-banner-Suzuki_AX-768x384.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" width=\"800\" height=\"300\"   \/><\/a><\/div>","protected":false},"excerpt":{"rendered":"<p>LATINA &#8211;\u00a0Geolocalizzare i casi di Covid-19, ovvero prendere la cartina geografica della provincia e la mappa delle strade cittadine di ogni Comune e verificare dove sono emersi i nuovi positivi. In questo modo, durante il lockdown a Fondi venne fuori che intere strade pullulavano di contagiati e in misura minore \u00e8 accaduto anche a Formia, [&hellip;]<\/p>\n","protected":false},"author":62,"featured_media":277240,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[2616],"tags":[69,661,2653,226,2651,2655,3171,23,2154,3170],"class_list":["post-277239","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sanita","tag-aprilia","tag-asl","tag-casati","tag-cisterna","tag-coronavirus","tag-covid-19","tag-geolocalizzazione","tag-latina","tag-notizie-di-latina","tag-sars-cov-2"],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/277239","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/users\/62"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/comments?post=277239"}],"version-history":[{"count":0,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/277239\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/media\/277240"}],"wp:attachment":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/media?parent=277239"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/categories?post=277239"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/tags?post=277239"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}