{"id":277552,"date":"2020-10-28T16:41:04","date_gmt":"2020-10-28T15:41:04","guid":{"rendered":"https:\/\/www.radioluna.it\/news\/?p=277552"},"modified":"2020-10-28T16:41:04","modified_gmt":"2020-10-28T15:41:04","slug":"mobilita-sostenibile-il-comune-di-latina-ammesso-a-un-finanziamento-di-63-371-mila-euro","status":"publish","type":"post","link":"https:\/\/www.radioluna.it\/news\/2020\/10\/mobilita-sostenibile-il-comune-di-latina-ammesso-a-un-finanziamento-di-63-371-mila-euro\/","title":{"rendered":"Mobilit\u00e0 sostenibile, il Comune di Latina ammesso a un finanziamento di 63.371 mila euro"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p style=\"text-align: justify;\"><strong>LATINA &#8211;<\/strong> Il Comune di Latina \u00e8 stato ammesso a un finanziamento di 63.371 euro per la realizzazione di specifiche misure dedicate alla mobilit\u00e0 sostenibile. Il Ministero dell\u2019Ambiente e della Tutela del Territorio e del Mare ha infatti inserito Latina fra i 12 Comuni che riceveranno fondi nell\u2019ambito del Programma di Incentivazione della Mobilit\u00e0 Urbana Sostenibile (PrIMUS). A quella somma il Comune aggiunger\u00e0 20.000 euro in co-finanziamento, fondi gi\u00e0 previsti in bilancio.<\/p>\n<p style=\"text-align: justify;\">&#8220;Siamo molto soddisfatti che sia stato riconosciuto il valore e l\u2019utilit\u00e0 del progetto presentato dal Comune, grazie al quale la citt\u00e0 avr\u00e0 a disposizione nuove risorse per proseguire sulla strada della mobilit\u00e0 sostenibile &#8211; ha detto l&#8217;assessore Dario Bellini &#8211;\u00a0 Il progetto grazie al quale il Ministero ci assegna i fondi in co-finanziamento sar\u00e0 riadeguato vista l\u2019emergenza COVID che stiamo vivendo, ma questo non cambia il nostro obiettivo: rendere Latina sempre pi\u00f9 sostenibile con scelte nuove e innovative che migliorino la vita delle persone nel rispetto dell\u2019ambiente&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<div id=\"radio-2172802326\" class=\"radio-dopo-il-contenuto radio-entity-placement\"><a href=\"https:\/\/concessionari-suzuki.it\/bodema\/\" aria-label=\"Bodema 1200&#215;600 banner Suzuki_AX\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2025\/05\/Bodema-1200x600-banner-Suzuki_AX.jpg\" alt=\"\"  srcset=\"https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2025\/05\/Bodema-1200x600-banner-Suzuki_AX.jpg 1200w, https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2025\/05\/Bodema-1200x600-banner-Suzuki_AX-768x384.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" width=\"800\" height=\"300\"   \/><\/a><\/div>","protected":false},"excerpt":{"rendered":"<p>LATINA &#8211; Il Comune di Latina \u00e8 stato ammesso a un finanziamento di 63.371 euro per la realizzazione di specifiche misure dedicate alla mobilit\u00e0 sostenibile. Il Ministero dell\u2019Ambiente e della Tutela del Territorio e del Mare ha infatti inserito Latina fra i 12 Comuni che riceveranno fondi nell\u2019ambito del Programma di Incentivazione della Mobilit\u00e0 Urbana [&hellip;]<\/p>\n","protected":false},"author":60,"featured_media":268704,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[735],"tags":[],"class_list":["post-277552","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-attualita"],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/277552","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/users\/60"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/comments?post=277552"}],"version-history":[{"count":0,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/277552\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/media\/268704"}],"wp:attachment":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/media?parent=277552"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/categories?post=277552"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/tags?post=277552"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}