{"id":278320,"date":"2020-11-11T07:20:27","date_gmt":"2020-11-11T06:20:27","guid":{"rendered":"https:\/\/www.radioluna.it\/news\/?p=278320"},"modified":"2020-11-11T07:17:44","modified_gmt":"2020-11-11T06:17:44","slug":"mario-cerca-coccole-e-da-affetto","status":"publish","type":"post","link":"https:\/\/www.radioluna.it\/news\/2020\/11\/mario-cerca-coccole-e-da-affetto\/","title":{"rendered":"Mario, cerca coccole e d\u00e0 affetto"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p style=\"text-align: justify;\"><strong>LATINA &#8211;<\/strong> <strong>MARI<\/strong>O strepitosa taglia media 5 anni, super affettuoso cerca continuamente il contatto umano, \u00e8 vivace e molto allegro. Cerchiamo una famiglia che possa amarlo (e abbracciarlo) come merita. Mario si trova a Latina, ma per una buona adozione potr\u00e0 raggiungere la sua nuova famiglia in tutto il centro nord.<\/p>\n<p style=\"text-align: justify;\">Per informazioni contattare <strong>Associazione amici del cane di Latina<\/strong>: 0773.662177 \u2013 334-7740414 (puoi inviarci anche un messaggio se non dovessimo rispondere)<\/p>\n<div id=\"radio-2093264909\" class=\"radio-dopo-il-contenuto radio-entity-placement\"><a href=\"https:\/\/concessionari-suzuki.it\/bodema\/\" aria-label=\"Bodema 1200&#215;600 banner Suzuki_AX\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2025\/05\/Bodema-1200x600-banner-Suzuki_AX.jpg\" alt=\"\"  srcset=\"https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2025\/05\/Bodema-1200x600-banner-Suzuki_AX.jpg 1200w, https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2025\/05\/Bodema-1200x600-banner-Suzuki_AX-768x384.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" width=\"800\" height=\"300\"   \/><\/a><\/div>","protected":false},"excerpt":{"rendered":"<p>LATINA &#8211; MARIO strepitosa taglia media 5 anni, super affettuoso cerca continuamente il contatto umano, \u00e8 vivace e molto allegro. Cerchiamo una famiglia che possa amarlo (e abbracciarlo) come merita. Mario si trova a Latina, ma per una buona adozione potr\u00e0 raggiungere la sua nuova famiglia in tutto il centro nord. Per informazioni contattare Associazione [&hellip;]<\/p>\n","protected":false},"author":62,"featured_media":278321,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[2239],"tags":[3186,3187,3049,23,2154],"class_list":["post-278320","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-amiciaquattrozampe","tag-adotta-un-cane","tag-amici-del-cane","tag-cane","tag-latina","tag-notizie-di-latina"],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/278320","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/users\/62"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/comments?post=278320"}],"version-history":[{"count":0,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/278320\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/media\/278321"}],"wp:attachment":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/media?parent=278320"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/categories?post=278320"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/tags?post=278320"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}