{"id":285232,"date":"2021-02-24T07:14:43","date_gmt":"2021-02-24T06:14:43","guid":{"rendered":"https:\/\/www.radioluna.it\/news\/?p=285232"},"modified":"2021-02-24T07:14:43","modified_gmt":"2021-02-24T06:14:43","slug":"i-quotidiani-locali-in-un-click-24-febbraio-2021","status":"publish","type":"post","link":"https:\/\/www.radioluna.it\/news\/2021\/02\/i-quotidiani-locali-in-un-click-24-febbraio-2021\/","title":{"rendered":"I quotidiani locali in un  click &#8211; 24 febbraio 2021"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p style=\"text-align: justify;\"><strong>LATINA<\/strong> &#8211; Qui trovate Prima Pagina, ora solo in versione web, per dare uno sguardo ai titoli di Latina Editoriale Oggi e Il Messaggero Latina.<\/p>\n<p><strong>ASCOLTA<\/strong><\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-285232-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2021\/02\/titoli-21.mp3?_=1\" \/><a href=\"https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2021\/02\/titoli-21.mp3\">https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2021\/02\/titoli-21.mp3<\/a><\/audio>\n<p>&nbsp;<\/p>\n<div id=\"radio-3362588171\" class=\"radio-dopo-il-contenuto radio-entity-placement\"><a href=\"https:\/\/concessionari-suzuki.it\/bodema\/\" aria-label=\"Bodema 1200&#215;600 banner Suzuki_AX\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2025\/05\/Bodema-1200x600-banner-Suzuki_AX.jpg\" alt=\"\"  srcset=\"https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2025\/05\/Bodema-1200x600-banner-Suzuki_AX.jpg 1200w, https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2025\/05\/Bodema-1200x600-banner-Suzuki_AX-768x384.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" width=\"800\" height=\"300\"   \/><\/a><\/div>","protected":false},"excerpt":{"rendered":"<p>LATINA &#8211; Qui trovate Prima Pagina, ora solo in versione web, per dare uno sguardo ai titoli di Latina Editoriale Oggi e Il Messaggero Latina. ASCOLTA &nbsp;<\/p>\n","protected":false},"author":60,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[2358],"tags":[3253,23,2154,3252],"class_list":["post-285232","post","type-post","status-publish","format-standard","hentry","category-titoli","tag-giornali","tag-latina","tag-notizie-di-latina","tag-prima-pagina"],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/285232","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/users\/60"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/comments?post=285232"}],"version-history":[{"count":0,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/285232\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/media?parent=285232"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/categories?post=285232"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/tags?post=285232"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}