{"id":290021,"date":"2021-05-08T11:10:23","date_gmt":"2021-05-08T09:10:23","guid":{"rendered":"https:\/\/www.radioluna.it\/news\/?p=290021"},"modified":"2021-05-15T09:24:52","modified_gmt":"2021-05-15T07:24:52","slug":"la-women-latina-calcio-in-cerca-della-vittoria","status":"publish","type":"post","link":"https:\/\/www.radioluna.it\/news\/2021\/05\/la-women-latina-calcio-in-cerca-della-vittoria\/","title":{"rendered":"La Women Latina Calcio in cerca della vittoria"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p style=\"text-align: justify;\">Dopo quattro gare decisamente avare di soddisfazioni, per la Women Latina Calcio 1932 \u00e8 arrivato il momento di raccogliere.\u00a0E l\u2019occasione pare quella giusta visto che domani pomeriggio le ragazze di mister Franz\u00e8 incontrano il Sora.\u00a0La formazione ciociara \u00e8 reduce dalla lezione subita dal Frosinone nel derby ed ha subito la bellezza di 25 gol nei 4 match giocati sinora.<\/p>\n<p style=\"text-align: justify;\">Dall\u2019altra parte le nerazzurre che, dopo aver raccolto plausi e complimenti per il gioco espresso, vogliono finalmente festeggiare la prima vittoria della stagione.<\/p>\n<p style=\"text-align: justify;\">Dovranno farlo, per\u00f2, senza Chiara Sausto, il cui infortunio la terr\u00e0 lontana dai campi anche per le tre partite che mancano alla fine della stagione. Anche le condizioni di Giada Liberti non sono le migliori, per un problema al piede che la tormenta da settimane. Il suo impiego si decider\u00e0 solo all\u2019immediata vigilia del match.<\/p>\n<p style=\"text-align: justify;\">Indisponibile anche la Piconi, espulsa domenica contro la Lazio Calcio a 5 Global.<\/p>\n<p style=\"text-align: justify;\">\u201cLa squadra ha lavorato bene come al solito \u2013 ammette mister Franz\u00e8 -. Visto come \u00e8 andata finora, l\u2019obiettivo \u00e8 migliorare partita dopo partita e farci trovare pronte per la prossima stagione, sperando che sia regolare&#8230;<\/p>\n<p style=\"text-align: justify;\">Se escludiamo l\u2019ultima partita, dove abbiamo affrontato una formazione semi professionistica, con ragazze che giocano a calcio di mestiere e che hanno fatto, nel calcio a 5, anche presenze in nazionale, per il resto ci siamo sempre comportate bene, anche se adesso, dopo aver tanto seminato, \u00e8 arrivato il momento anche di raccogliere.<\/p>\n<p style=\"text-align: justify;\">Col Sora vogliamo vincere e prenderci quella soddisfazione che sia a Monterotondo che a Nettuno meritavamo ampiamente\u201d.<\/p>\n<p style=\"text-align: justify;\">L\u2019appuntamento \u00e8 per domani pomeriggio, 9 maggio, a Sora per il match contro le padrone di casa della Vis Sora 07. Calcio di inizio alle ore 16 e 30. Arbitro dell\u2019incontro Marco Capobianchi della sezione di Tivoli.<\/p>\n<div id=\"radio-2446271025\" class=\"radio-dopo-il-contenuto radio-entity-placement\"><a href=\"https:\/\/concessionari-suzuki.it\/bodema\/\" aria-label=\"Bodema 1200&#215;600 banner Suzuki_AX\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2025\/05\/Bodema-1200x600-banner-Suzuki_AX.jpg\" alt=\"\"  srcset=\"https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2025\/05\/Bodema-1200x600-banner-Suzuki_AX.jpg 1200w, https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2025\/05\/Bodema-1200x600-banner-Suzuki_AX-768x384.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" width=\"800\" height=\"300\"   \/><\/a><\/div>","protected":false},"excerpt":{"rendered":"<p>Dopo quattro gare decisamente avare di soddisfazioni, per la Women Latina Calcio 1932 \u00e8 arrivato il momento di raccogliere.\u00a0E l\u2019occasione pare quella giusta visto che domani pomeriggio le ragazze di mister Franz\u00e8 incontrano il Sora.\u00a0La formazione ciociara \u00e8 reduce dalla lezione subita dal Frosinone nel derby ed ha subito la bellezza di 25 gol nei [&hellip;]<\/p>\n","protected":false},"author":5430,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-290021","post","type-post","status-publish","format-standard","hentry","category-sport"],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/290021","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/users\/5430"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/comments?post=290021"}],"version-history":[{"count":0,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/290021\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/media?parent=290021"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/categories?post=290021"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/tags?post=290021"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}