{"id":292466,"date":"2021-06-16T10:07:52","date_gmt":"2021-06-16T08:07:52","guid":{"rendered":"https:\/\/www.radioluna.it\/news\/?p=292466"},"modified":"2021-06-16T13:08:24","modified_gmt":"2021-06-16T11:08:24","slug":"torna-il-premio-lido-green-marina-di-latina-allo-stabilimento-piu-virtuoso","status":"publish","type":"post","link":"https:\/\/www.radioluna.it\/news\/2021\/06\/torna-il-premio-lido-green-marina-di-latina-allo-stabilimento-piu-virtuoso\/","title":{"rendered":"Torna il premio Lido Green Marina di Latina allo stabilimento pi\u00f9 virtuoso"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p style=\"text-align: justify;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-292467\" src=\"https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2021\/06\/lido-green.jpg\" alt=\"\" width=\"521\" height=\"360\" \/>LATINA<\/strong> &#8211; Torna per il secondo anno consecutivo il <strong>Premio Lido Green Marina di Latina<\/strong>, l\u2019iniziativa ambientale promossa dall&#8217;Azienda per i Beni Comuni di Latina in collaborazione con il Comune di Latina. <strong>Il progetto si rivolge a tutti gli stabilimenti balneari e chioschi del lungomare di Latina<\/strong> e mira a valorizzare e sostenere l&#8217;impegno degli operatori che, nel corso della stagione balneare2021, privilegiano la sostenibilit\u00e0 e il basso impatto ambientale mettendo a punto una serie di strategie green in linea con l\u2019ordinanza comunale \u201cLatina Plastic Free\u201d n. 141\/2021.<br \/>\n\u201cIl Premio Lido Green Marina di Latina &#8211; dichiara<strong> il Presidente del CdA ABC, Gustavo Giorgi<\/strong> &#8211; si inserisce nell&#8217;ambito della campagna di sensibilizzazione e comunicazione che ABC, in sinergia con l&#8217;Amministrazione Comunale, sta mettendo in atto sul litorale per promuovere una cultura della sostenibilit\u00e0 e sviluppare una nuova consapevolezza ecologica per la salvaguardia dell&#8217;ambiente e, in particolare, dell&#8217;ecosistema marino. Anche quest&#8217;anno Latina si \u00e8 confermata Bandiera Blu, prestigioso riconoscimento che certifica la qualit\u00e0 di spiagge e acque di balneazione assegnato dalla FEE (Foundation for Environmental Education). Un&#8217;importante conferma che premia gli sforzi profusi negli ultimi anni dalla fattiva collaborazione tra ABC e Amministrazione sul fronte della qualit\u00e0 ambientale e dei servizi offerti sull&#8217;arenile\u201d.<br \/>\n\u201cLa ABC &#8211; spiega<strong> il Direttore Generale ABC, Silvio Ascoli &#8211;<\/strong> distribuir\u00e0 materiale informativo per il corretto smaltimento, gadget eco sostenibili e, presso gli stabilimenti, conetti anti-cicche per la lotta all&#8217;abbandono dei mozziconi di sigarette in spiaggia. Il Premio Lido Green Marina di Latina mira a diventare un appuntamento fisso per i cittadini e gli operatori del territorio, e un&#8217;occasione per incentivare e condividere le buone pratiche e i comportamenti virtuosi, perch\u00e9 solamente insieme \u00a0si pu\u00f2 raggiungere un grande risultato\u201d. (nella foto il presidente e il direttore di Abc, Gustavo Giorgi e Silvio Ascoli)<\/p>\n<div id=\"radio-3225247938\" class=\"radio-dopo-il-contenuto radio-entity-placement\"><a href=\"https:\/\/concessionari-suzuki.it\/bodema\/\" aria-label=\"Bodema 1200&#215;600 banner Suzuki_AX\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2025\/05\/Bodema-1200x600-banner-Suzuki_AX.jpg\" alt=\"\"  srcset=\"https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2025\/05\/Bodema-1200x600-banner-Suzuki_AX.jpg 1200w, https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2025\/05\/Bodema-1200x600-banner-Suzuki_AX-768x384.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" width=\"800\" height=\"300\"   \/><\/a><\/div>","protected":false},"excerpt":{"rendered":"<p>LATINA &#8211; Torna per il secondo anno consecutivo il Premio Lido Green Marina di Latina, l\u2019iniziativa ambientale promossa dall&#8217;Azienda per i Beni Comuni di Latina in collaborazione con il Comune di Latina. Il progetto si rivolge a tutti gli stabilimenti balneari e chioschi del lungomare di Latina e mira a valorizzare e sostenere l&#8217;impegno degli [&hellip;]<\/p>\n","protected":false},"author":60,"featured_media":288451,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[12],"tags":[4013,23,4775],"class_list":["post-292466","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ambiente","tag-abc-latina","tag-latina","tag-lido-green-latina"],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/292466","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/users\/60"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/comments?post=292466"}],"version-history":[{"count":0,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/292466\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/media\/288451"}],"wp:attachment":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/media?parent=292466"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/categories?post=292466"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/tags?post=292466"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}