{"id":302638,"date":"2021-12-14T18:17:05","date_gmt":"2021-12-14T17:17:05","guid":{"rendered":"https:\/\/www.radioluna.it\/news\/?p=302638"},"modified":"2021-12-17T10:35:11","modified_gmt":"2021-12-17T09:35:11","slug":"testaccio-raccontato-da-favino-brizzi-e-jasmine-trinca","status":"publish","type":"post","link":"https:\/\/www.radioluna.it\/news\/2021\/12\/testaccio-raccontato-da-favino-brizzi-e-jasmine-trinca\/","title":{"rendered":"Testaccio raccontato da Favino, Brizzi e Jasmine Trinca"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p style=\"text-align: justify;\">Scoprire lo storico quartiere romano di Testaccio guidati da Pier Francesco Favino e Anna Ferzetti, Fausto Brizzi, Giuseppe Cederna, Michela Cescon, Paolo Conticini, Piera Detassis, Gigi Di Biagio, Sabrina Impacciatore, Lucia Mascino, Maura Mora, Les Bergmann e Jasmine Trinca. In occasione delle celebrazioni per i cento anni dalla fondazione del rione, le Guide di Repubblica, pubblicano nella collana \u201cQuartiere Italia\u201d un volume tematico, quasi trecento pagine di storie, consigli, interviste, testimonianze e passeggiate. &#8220;Un intero capitolo \u00e8 dedicato a dodici Passeggiate tematiche, che esplorano il rione alla scoperta, ad esempio, dell\u2019archeologia, dei set cinematografici e del mercato rionale, oltre che delle attivit\u00e0 da svolgere con i bambini e dei luoghi letterari e del ricordo&#8221;, spiegano i curatori. C&#8217;\u00e8 anche una sezione di foto d&#8217;epoca oltre alle informazioni di servizio su dove mangiare, comprare e dormire.<\/p>\n<p style=\"text-align: justify;\">Lo scrittore Fulvio Abbate, in apertura del volume, firma un\u2019ideale passeggiata tra le strade e i simboli del rione, tra ricordi, curiosit\u00e0 e accadimenti storici, mentre le venti interviste della sezione \u201cVolti &amp; Storie\u201d testimoniano il vivace tessuto sociale di Testaccio, raccogliendo le voci di fondazioni, istituzioni e associazioni come, tra gli altri, Romaeuropa, il Teatro Vittoria, il Gay Center, l\u2019universit\u00e0 RomaTre, l\u2019Azienda Speciale Palaexpo e il Roma Club.<\/p>\n<p style=\"text-align: justify;\">\u00abDa Testaccio \u00e8 transitata la storia di Roma, quella aperta a tutte le sponde del Mediterraneo, e dove oggi sono aperti laboratori culturali, fondazioni d\u2019arte, cinema di culto e teatri. Noi con questa Guida vogliamo aiutare chi adora Testaccio a scoprire i pi\u00f9 suggestivi angoli del rione, con i suoi personaggi, i suoi profumi, i suoi indirizzi, le sue tendenze\u00bb, scrive il direttore delle Guide di Repubblica, Giuseppe Cerasa, nella sua introduzione.<\/p>\n<p style=\"text-align: justify;\">\n<div id=\"radio-2478152854\" class=\"radio-dopo-il-contenuto radio-entity-placement\"><a href=\"https:\/\/concessionari-suzuki.it\/bodema\/\" aria-label=\"Bodema 1200&#215;600 banner Suzuki_AX\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2025\/05\/Bodema-1200x600-banner-Suzuki_AX.jpg\" alt=\"\"  srcset=\"https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2025\/05\/Bodema-1200x600-banner-Suzuki_AX.jpg 1200w, https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2025\/05\/Bodema-1200x600-banner-Suzuki_AX-768x384.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" width=\"800\" height=\"300\"   \/><\/a><\/div>","protected":false},"excerpt":{"rendered":"<p>Scoprire lo storico quartiere romano di Testaccio guidati da Pier Francesco Favino e Anna Ferzetti, Fausto Brizzi, Giuseppe Cederna, Michela Cescon, Paolo Conticini, Piera Detassis, Gigi Di Biagio, Sabrina Impacciatore, Lucia Mascino, Maura Mora, Les Bergmann e Jasmine Trinca. In occasione delle celebrazioni per i cento anni dalla fondazione del rione, le Guide di Repubblica, [&hellip;]<\/p>\n","protected":false},"author":62,"featured_media":302639,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[735],"tags":[],"class_list":["post-302638","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-attualita"],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/302638","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/users\/62"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/comments?post=302638"}],"version-history":[{"count":0,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/302638\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/media\/302639"}],"wp:attachment":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/media?parent=302638"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/categories?post=302638"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/tags?post=302638"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}