{"id":341613,"date":"2023-11-29T18:13:01","date_gmt":"2023-11-29T17:13:01","guid":{"rendered":"https:\/\/www.radioluna.it\/news\/?p=341613"},"modified":"2023-11-29T18:13:01","modified_gmt":"2023-11-29T17:13:01","slug":"potenziato-lorganico-della-guardia-di-finanza-di-latina","status":"publish","type":"post","link":"https:\/\/www.radioluna.it\/news\/2023\/11\/potenziato-lorganico-della-guardia-di-finanza-di-latina\/","title":{"rendered":"Potenziato l&#8217;organico della Guardia di Finanza di Latina"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p style=\"text-align: justify;\"><strong>LATINA &#8211;<\/strong> Prosegue il percorso di potenziamento delle Fiamme Gialle impiegate nei reparti del Comando Provinciale della Guardia di Finanza di Latina.<\/p>\n<p style=\"text-align: justify;\">Dalla scorsa estate sono stati infatti assegnati alla provincia pontina, nell\u2019ambito delle ordinarie manovre di impiego e al termine dei corsi formativi, 16 nuovi militari e un nuovo ufficiale, tutti inquadrati in reparti territoriali e operativi che svolgono attivit\u00e0 \u201csul campo\u201d.<\/p>\n<p style=\"text-align: justify;\">In particolare, sono stati destinati 12 nuovi ispettori e 4 tra sovrintendenti e appuntati e finanzieri e, degli ispettori, 8, di et\u00e0 compresa tra 22 e 28 anni, giungono in terra pontina al termine del corso di formazione triennale presso la Scuola Ispettori e Sovrintendenti di L\u2019Aquila. Si tratta di un periodo addestrativo e didattico particolarmente impegnativo e di alti contenuti specialistici, che affianca un rigoroso addestramento militare e di polizia a un percorso di studi di livello universitario che culmina nel conseguimento della laurea di primo livello in \u201cOperatore giuridico d\u2019impresa\u201d. Due dei giovani Marescialli giungono al termine di un\u2019esperienza annuale in qualit\u00e0 di istruttore presso la Scuola Nautica di Gaeta, avviata lo scorso anno al termine del corso svolto alla Scuola de L\u2019Aquila.<\/p>\n<p style=\"text-align: justify;\">Tra le nuove risorse assegnate, vi sono anche n. 3 militari specializzati A.T.P.I. (anti terrorismo e pronto impiego), inquadrati nel Gruppo di Formia, reparto che dispone di una Sezione Operativa interamente composta da militari di questa componente specialistica, i cc.dd. baschi verdi, che ha competenza su tutta la provincia. Competenza provinciale ha anche il Nucleo di polizia economico-finanziaria di Latina, reparto dalla spiccata proiezione investigativa, che, oltre ai militari giunti con le manovre ordinarie, ha ricevuto nel complesso n. 4 neoispettori, ovvero le risorse con particolare taglio investigativo e operativo da impiegare nelle indagini e nelle attivit\u00e0 di controllo e contrasto alle frodi nei vari settori di competenza del Corpo.<\/p>\n<p style=\"text-align: justify;\">Oltre alle articolazioni con competenza provinciale, alcuni militari sono stati distribuiti sugli altri presidi territoriali, con sede nei comuni di Latina, Aprilia, Cisterna e Formia e competenza in diverse aree della provincia, onde ottenere in tal modo un capillare potenziamento degli organici in tutta l\u2019area provinciale.<\/p>\n<p style=\"text-align: justify;\">Al Gruppo di Formia \u00e8 giunto inoltre un nuovo ufficiale, il Sten. Vincenzo Scognamiglio, al termine del corso di formazione frequentato all\u2019Accademia di Bergamo. L\u2019Ufficiale proviene dalle fila del ruolo ispettori del Corpo ed ha una stratificata esperienza in investigazioni di carattere finanziario e in indagini di polizia giudiziaria, che metter\u00e0 al servizio del nuovo reparto, impegnato in un\u2019area notoriamente delicata ed esposta a peculiari fenomeni di criminalit\u00e0 economico-finanziaria anche di matrice organizzata.<\/p>\n<p>Il Comandante Provinciale,\u00a0Col. Giovanni Marchetti, nel rituale incontro di benvenuto, ha ricevuto ufficialmente i nuovi arrivati alla presenza dei vari comandanti responsabili, e, nell\u2019augurare a tutti loro un buon lavoro, li ha esortati a dare il massimo nelle diverse mansioni che andranno a svolgere, da affrontare con entusiasmo e professionalit\u00e0 in settori particolarmente esposti a rischi di infiltrazione della criminalit\u00e0 nell\u2019economia legale.<\/p>\n<p>Le nuove assegnazioni si inseriscono\u00a0nell\u2019avviato e preannunciato percorso di potenziamento degli organici\u00a0in corso presso i reparti del Comando Provinciale, tuttora in corso, disposto in ragione della continua crescita nell\u2019area del tessuto economico nonch\u00e9 dei rischi di frodi e illegalit\u00e0 economico-finanziarie, concreto segnale dell\u2019attenzione del Corpo al territorio e ai cittadini della provincia pontina; tali interventi si pongono peraltro in linea e nel solco della strategia d\u2019azione da tempo promossa dalla locale Prefettura al fine di pervenire a una graduale potenziamento del dispositivo di sicurezza e legalit\u00e0 operante a livello provinciale, in sinergia con le altre forze di polizia.<\/p>\n<p>Si tratta, infatti di risorse preziose che renderanno ancora pi\u00f9 incisiva la presenza delle Fiamme Gialle, destinate a rafforzare il presidio di sicurezza economico-finanziaria e le\u00a0attivit\u00e0 a contrasto delle frodi fiscali, al riciclaggio, all\u2019indebita percezione di fondi pubblici ed alle infiltrazioni della criminalit\u00e0 organizzata nel sistema economico legale, contribuendo a preservare la leale concorrenza tra gli operatori economici e a promuovere prospettive di crescita sane del mercato del lavoro e della produzione, a tutela delle libert\u00e0 economiche di tutti i cittadini e delle imprese onesti.<\/p>\n<div id=\"radio-2679108590\" class=\"radio-dopo-il-contenuto radio-entity-placement\"><a href=\"https:\/\/concessionari-suzuki.it\/bodema\/\" aria-label=\"Bodema 1200&#215;600 banner Suzuki_AX\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2025\/05\/Bodema-1200x600-banner-Suzuki_AX.jpg\" alt=\"\"  srcset=\"https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2025\/05\/Bodema-1200x600-banner-Suzuki_AX.jpg 1200w, https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2025\/05\/Bodema-1200x600-banner-Suzuki_AX-768x384.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" width=\"800\" height=\"300\"   \/><\/a><\/div>","protected":false},"excerpt":{"rendered":"<p>LATINA &#8211; Prosegue il percorso di potenziamento delle Fiamme Gialle impiegate nei reparti del Comando Provinciale della Guardia di Finanza di Latina. Dalla scorsa estate sono stati infatti assegnati alla provincia pontina, nell\u2019ambito delle ordinarie manovre di impiego e al termine dei corsi formativi, 16 nuovi militari e un nuovo ufficiale, tutti inquadrati in reparti [&hellip;]<\/p>\n","protected":false},"author":60,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[7,2428],"tags":[],"class_list":["post-341613","post","type-post","status-publish","format-standard","hentry","category-cronaca","category-primo-piano"],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/341613","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/users\/60"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/comments?post=341613"}],"version-history":[{"count":0,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/341613\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/media?parent=341613"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/categories?post=341613"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/tags?post=341613"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}