{"id":381344,"date":"2025-07-14T17:08:23","date_gmt":"2025-07-14T15:08:23","guid":{"rendered":"https:\/\/www.radioluna.it\/news\/?p=381344"},"modified":"2025-07-15T09:28:59","modified_gmt":"2025-07-15T07:28:59","slug":"priverno-precipita-dal-tetto-di-casa-per-controllare-le-grondaie","status":"publish","type":"post","link":"https:\/\/www.radioluna.it\/news\/2025\/07\/priverno-precipita-dal-tetto-di-casa-per-controllare-le-grondaie\/","title":{"rendered":"Priverno, precipita dal tetto di casa per controllare le grondaie"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p style=\"text-align: justify;\" data-start=\"284\" data-end=\"476\">Paura questa mattina a Priverno dove un uomo di 74 anni \u00e8 precipitato dal tetto della propria abitazione mentre stava verificando i lavori alle grondaie.\u00a0L\u2019anziano, secondo una prima ricostruzione, sarebbe salito sul tetto per controllare l\u2019esito di alcuni interventi appena eseguiti, ma avrebbe perso l\u2019equilibrio, cadendo da un\u2019altezza di circa 10 metri.\u00a0L\u2019allarme \u00e8 scattato immediatamente: sul posto sono intervenuti i Carabinieri della Stazione di Priverno e i sanitari del 118, che hanno richiesto l\u2019intervento dell\u2019elisoccorso. Il 74enne \u00e8 stato trasportato d\u2019urgenza in un ospedale di Roma.\u00a0Le sue condizioni sono al vaglio dei medici. I Carabinieri stanno proseguendo gli accertamenti per chiarire con precisione la dinamica dell\u2019accaduto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Paura questa mattina a Priverno dove un uomo di 74 anni \u00e8 precipitato dal tetto della propria abitazione mentre stava verificando i lavori alle grondaie.\u00a0L\u2019anziano, secondo una prima ricostruzione, sarebbe salito sul tetto per controllare l\u2019esito di alcuni interventi appena eseguiti, ma avrebbe perso l\u2019equilibrio, cadendo da un\u2019altezza di circa 10 metri.\u00a0L\u2019allarme \u00e8 scattato immediatamente: [&hellip;]<\/p>\n","protected":false},"author":5443,"featured_media":381345,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[7,2428],"tags":[],"class_list":["post-381344","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cronaca","category-primo-piano"],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/381344","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/users\/5443"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/comments?post=381344"}],"version-history":[{"count":1,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/381344\/revisions"}],"predecessor-version":[{"id":381346,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/381344\/revisions\/381346"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/media\/381345"}],"wp:attachment":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/media?parent=381344"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/categories?post=381344"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/tags?post=381344"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}