{"id":381610,"date":"2025-07-17T14:15:37","date_gmt":"2025-07-17T12:15:37","guid":{"rendered":"https:\/\/www.radioluna.it\/news\/?p=381610"},"modified":"2025-07-17T14:15:37","modified_gmt":"2025-07-17T12:15:37","slug":"il-comune-di-minturno-celebra-lanno-santo-con-le-visite-guidate-gratuite-alle-chiese-cittadine","status":"publish","type":"post","link":"https:\/\/www.radioluna.it\/news\/2025\/07\/il-comune-di-minturno-celebra-lanno-santo-con-le-visite-guidate-gratuite-alle-chiese-cittadine\/","title":{"rendered":"Il Comune di Minturno celebra l\u2019Anno Santo con le visite guidate gratuite alle Chiese cittadine"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p style=\"text-align: justify;\"><strong>MINTURNO<\/strong> &#8211;\u00a0 In occasione dell&#8217;Anno Santo, il Comune di Minturno promuove il programma di visite guidate gratuite \u201cGiubileo a Minturno tra collina e mare\u201d, per valorizzare il patrimonio storico, artistico e religioso custodito nelle Chiese del territorio. Un percorso che unisce cultura e spiritualit\u00e0.<\/p>\n<p style=\"text-align: justify;\">Dopo le prime due tappe, che hanno visto esplorare la Chiesa di San Francesco e la \u2018Cattedrale\u2019 di San Pietro a Minturno (6 luglio), e la Chiesa Parrocchiale di San Leonardo Abate a Tufo (12 luglio), il calendario prosegue con la visita in programma il 20 luglio nella Chiesa Parrocchiale di San Nicandro Martire a Tremensuoli;.<\/p>\n<p style=\"text-align: justify;\">\u201cIl programma di visite guidate gratuite \u2018Giubileo a Minturno tra collina e mare\u2019 rappresenta un&#8217;occasione straordinaria per potenziare l&#8217;attrattivit\u00e0 turistica del nostro territorio \u2015 dichiara l&#8217;Assessore al Turismo\u00a0Giuseppe Pensiero\u00a0\u2015 Attraverso la valorizzazione delle nostre chiese, veri e propri scrigni di storia e arte, offriamo ai visitatori un&#8217;immersione profonda nella cultura e nella spiritualit\u00e0 locale. Questa proposta \u2015 aggiunge l&#8217;Assessore\u00a0Pensiero\u00a0\u2015 \u00e8 pensata per arricchire l&#8217;offerta ricettiva e dare nuovi stimoli ai flussi turistici, invitando a scoprire un lato inedito e affascinante di Minturno e le sue frazioni, sia per chi soggiorna sulla costa che per chi esplora l&#8217;entroterra\u201d.<\/p>\n<p style=\"text-align: justify;\">LE ALTRE TAPPE &#8211;\u00a0 Il 26 luglio, Chiesa Parrocchiale di Santa Maria Infante; 10 agosto, Chiesa Parrocchiale di San Giuseppe a Pulcherini; 16 agosto, Chiesa Parrocchiale di San Biagio a Marina di Minturno; 22 agosto, Chiesa Parrocchiale di Sant\u2019Albina e Chiesa Parrocchiale dell\u2019Immacolata a Scauri; si conclude il 7 settembre con il tour alla Chiesa di Maria SS. della Libera e Chiesa di SS. Annunziata a Minturno.<\/p>\n<p style=\"text-align: justify;\">Le visite guidate, condotte dalla guida turistica\u00a0Valentina Treglia, sono gratuite e aperte a tutti: \u201c\u00c8 un onore e un piacere accompagnare i visitatori in questo viaggio attraverso la storia e la fede a Minturno \u2015 afferma \u2015 Ogni chiesa racchiude storie uniche, opere e iconografie di grande valore. Poterle condividere, specialmente in un&#8217;occasione cos\u00ec speciale come l&#8217;Anno Santo, rende ogni visita un&#8217;esperienza davvero emozionante\u201d.<\/p>\n<p style=\"text-align: justify;\">Per prenotare la propria partecipazione, \u00e8 sufficiente contattare la guida Valentina Treglia via WhatsApp al numero: 347 0720049. Per i possessori della Welcome Card il posto \u00e8 garantito, previa prenotazione entro 24 ore dalla data\u00a0dell&#8217;evento.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>MINTURNO &#8211;\u00a0 In occasione dell&#8217;Anno Santo, il Comune di Minturno promuove il programma di visite guidate gratuite \u201cGiubileo a Minturno tra collina e mare\u201d, per valorizzare il patrimonio storico, artistico e religioso custodito nelle Chiese del territorio. Un percorso che unisce cultura e spiritualit\u00e0. Dopo le prime due tappe, che hanno visto esplorare la Chiesa [&hellip;]<\/p>\n","protected":false},"author":62,"featured_media":381612,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16,734],"tags":[],"class_list":["post-381610","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-appuntamenti","category-evidenza"],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/381610","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/users\/62"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/comments?post=381610"}],"version-history":[{"count":1,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/381610\/revisions"}],"predecessor-version":[{"id":381613,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/381610\/revisions\/381613"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/media\/381612"}],"wp:attachment":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/media?parent=381610"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/categories?post=381610"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/tags?post=381610"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}