{"id":381973,"date":"2025-07-23T07:14:10","date_gmt":"2025-07-23T05:14:10","guid":{"rendered":"https:\/\/www.radioluna.it\/news\/?p=381973"},"modified":"2025-07-23T07:14:10","modified_gmt":"2025-07-23T05:14:10","slug":"atti-persecutori-e-minacce-era-ricercato-rintracciato-a-san-felice-circeo-dalla-polizia-di-stato-di-terracina","status":"publish","type":"post","link":"https:\/\/www.radioluna.it\/news\/2025\/07\/atti-persecutori-e-minacce-era-ricercato-rintracciato-a-san-felice-circeo-dalla-polizia-di-stato-di-terracina\/","title":{"rendered":"Atti persecutori e minacce. Era ricercato,  rintracciato a San Felice Circeo dalla Polizia di Stato di Terracina"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p>SAN FELICE CIRCEO &#8211; Era ricercato per l\u2019esecuzione dell\u2019ordinanza di aggravamento della misura cautelare, scovato a San Felice. E\u2019 un\u2019uomo classe 1985, noto alle forze di polizia per i suoi precedenti, gi\u00e0 sottoposto alla sorveglianza speciale e destinatario di una misura cautelare del divieto di avvicinamento alla persona offesa. La vittima ha sporto denuncia dopo essere stato minacciato di morte dell\u2019uomo, per questioni inerenti rapporti commerciali tra i due, l\u2019aveva inondato di messaggi, tutti dal contenuto intimidatorio e minaccioso, accusandolo di aver avuto una relazione con la sua ex compagna. Nonostante l\u2019applicazione della misura e del dispositivo elettronico, in pi\u00f9 occasioni aveva per\u00f2 violato le prescrizioni impostegli, tagliando il dispositivo elettronico di controllo poco dopo la sua applicazione. La misura restrittiva era rimasta ineseguita in quanto il soggetto si era reso si era reso irreperibile. Ieri mattina gli agenti del Commissariato di Terracina, durante servizi di controllo del territorio svolti anche nel territorio del Comune di San Felice Circeo, lo hanno intercettato e riconoscendolo lo hanno fermato e sottoposto ad accertamenti a seguito dei quali l\u2019uomo \u00e8 stato dichiarato in arresto in esecuzione dell\u2019aggravamento della misura imposto dall\u2019Autorit\u00e0 Giudiziaria.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SAN FELICE CIRCEO &#8211; Era ricercato per l\u2019esecuzione dell\u2019ordinanza di aggravamento della misura cautelare, scovato a San Felice. E\u2019 un\u2019uomo classe 1985, noto alle forze di polizia per i suoi precedenti, gi\u00e0 sottoposto alla sorveglianza speciale e destinatario di una misura cautelare del divieto di avvicinamento alla persona offesa. La vittima ha sporto denuncia dopo [&hellip;]<\/p>\n","protected":false},"author":5444,"featured_media":372989,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[7,2428],"tags":[],"class_list":["post-381973","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cronaca","category-primo-piano"],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/381973","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/users\/5444"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/comments?post=381973"}],"version-history":[{"count":1,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/381973\/revisions"}],"predecessor-version":[{"id":381974,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/381973\/revisions\/381974"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/media\/372989"}],"wp:attachment":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/media?parent=381973"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/categories?post=381973"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/tags?post=381973"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}