{"id":382279,"date":"2025-07-28T15:16:00","date_gmt":"2025-07-28T13:16:00","guid":{"rendered":"https:\/\/www.radioluna.it\/news\/?p=382279"},"modified":"2025-07-28T18:11:45","modified_gmt":"2025-07-28T16:11:45","slug":"aprilia-tenta-il-suicidio-dal-balcone-di-casa-61enne-salvato-dai-carabinieri","status":"publish","type":"post","link":"https:\/\/www.radioluna.it\/news\/2025\/07\/aprilia-tenta-il-suicidio-dal-balcone-di-casa-61enne-salvato-dai-carabinieri\/","title":{"rendered":"Aprilia, tenta il suicidio dal balcone di casa: 61enne salvato dai Carabinieri"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p style=\"text-align: justify;\" data-start=\"309\" data-end=\"641\">Tragedia sfiorata nella serata di ieri ad Aprilia, in provincia di Latina, dove un uomo di 61 anni ha minacciato di togliersi la vita lanciandosi dal balcone della propria abitazione. Provvidenziale l\u2019intervento dei Carabinieri della Sezione Radiomobile del Reparto Territoriale di Aprilia, che sono riusciti a salvarlo in extremis.\u00a0La richiesta di aiuto \u00e8 arrivata al numero unico per le emergenze 112. I militari, intervenuti con tempestivit\u00e0, si sono trovati davanti una scena drammatica: l\u2019uomo, in evidente stato di agitazione, si trovava gi\u00e0 sul balcone e, oltre a minacciare i familiari presenti in casa e gli stessi Carabinieri, annunciava l\u2019intenzione di lanciarsi nel vuoto. Con grande sangue freddo, i militari si sono avvicinati cercando di instaurare un dialogo, nonostante l\u2019uomo si mostrasse ostile e verbalmente aggressivo. In un momento di distrazione, sfruttando la loro prontezza e determinazione, sono riusciti ad afferrarlo e a metterlo in salvo, evitando il peggio. L\u2019intervento ha permesso di riportare l\u2019uomo all\u2019interno dell\u2019abitazione, dove \u00e8 stato successivamente affidato alle cure del personale sanitario.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tragedia sfiorata nella serata di ieri ad Aprilia, in provincia di Latina, dove un uomo di 61 anni ha minacciato di togliersi la vita lanciandosi dal balcone della propria abitazione. Provvidenziale l\u2019intervento dei Carabinieri della Sezione Radiomobile del Reparto Territoriale di Aprilia, che sono riusciti a salvarlo in extremis.\u00a0La richiesta di aiuto \u00e8 arrivata al [&hellip;]<\/p>\n","protected":false},"author":5443,"featured_media":375810,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[7,2428],"tags":[],"class_list":["post-382279","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cronaca","category-primo-piano"],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/382279","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/users\/5443"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/comments?post=382279"}],"version-history":[{"count":1,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/382279\/revisions"}],"predecessor-version":[{"id":382280,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/382279\/revisions\/382280"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/media\/375810"}],"wp:attachment":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/media?parent=382279"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/categories?post=382279"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/tags?post=382279"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}