{"id":382281,"date":"2025-07-28T16:01:44","date_gmt":"2025-07-28T14:01:44","guid":{"rendered":"https:\/\/www.radioluna.it\/news\/?p=382281"},"modified":"2025-07-29T16:06:23","modified_gmt":"2025-07-29T14:06:23","slug":"virus-west-nile-seconda-vittima-in-provincia-di-latina","status":"publish","type":"post","link":"https:\/\/www.radioluna.it\/news\/2025\/07\/virus-west-nile-seconda-vittima-in-provincia-di-latina\/","title":{"rendered":"Virus West Nile, seconda vittima nel Lazio e 16 nuovi casi"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p style=\"text-align: justify;\">Seconda vittima del virus west Nile nel Lazio. Il paziente di 77 anni \u00e8 deceduto all\u2019alba di oggi all&#8217;istituto Spallanzani di Roma aveva patologie croniche ed era reduce da un trapianto cardiaco. Si ritiene che l\u2019esposizione al virus sia avvenuta durante un recente soggiorno a Baia Domizia, in provincia di Caserta. La Regione comunica che sono salite a 44 le infezioni confermate nel 2025, con 16 nuovi casi accertati, tra cui il nuovo decesso. Dei casi totali, 41 sono stati registrati in provincia di Latina, 2 in provincia di Roma e 1 fuori Regione. I Comuni pontini pi\u00f9 colpiti sono Aprilia, Latina, Fondi, Pontinia, Sabaudia, Sezze, Cisterna e Priverno. I due casi romani provengono invece da Anzio e Nettuno. Attualmente, 18 pazienti sono ricoverati nei reparti ordinari, 2 in terapia intensiva, 19 in cura a casa e 3 gi\u00e0 dimessi. \u00c8 stata intanto rafforzata la sorveglianza veterinaria nelle Asl di Frosinone, RM5, RM6 e Latina, mentre proseguono le attivit\u00e0 di informazione rivolte ai medici di base e ai pediatri per una diagnosi precoce.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Seconda vittima del virus west Nile nel Lazio. Il paziente di 77 anni \u00e8 deceduto all\u2019alba di oggi all&#8217;istituto Spallanzani di Roma aveva patologie croniche ed era reduce da un trapianto cardiaco. Si ritiene che l\u2019esposizione al virus sia avvenuta durante un recente soggiorno a Baia Domizia, in provincia di Caserta. La Regione comunica che [&hellip;]<\/p>\n","protected":false},"author":5443,"featured_media":382282,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[7,2428],"tags":[],"class_list":["post-382281","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cronaca","category-primo-piano"],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/382281","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/users\/5443"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/comments?post=382281"}],"version-history":[{"count":3,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/382281\/revisions"}],"predecessor-version":[{"id":382304,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/382281\/revisions\/382304"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/media\/382282"}],"wp:attachment":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/media?parent=382281"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/categories?post=382281"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/tags?post=382281"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}