{"id":382340,"date":"2025-07-29T14:39:03","date_gmt":"2025-07-29T12:39:03","guid":{"rendered":"https:\/\/www.radioluna.it\/news\/?p=382340"},"modified":"2025-07-31T15:01:59","modified_gmt":"2025-07-31T13:01:59","slug":"west-nile-muore-un-86enne-allospedale-santa-maria-goretti-di-latina-e-la-terza-vittima-nel-lazio","status":"publish","type":"post","link":"https:\/\/www.radioluna.it\/news\/2025\/07\/west-nile-muore-un-86enne-allospedale-santa-maria-goretti-di-latina-e-la-terza-vittima-nel-lazio\/","title":{"rendered":"West Nile, muore un 86enne all&#8217;ospedale Santa Maria Goretti di Latina: \u00e8 la terza vittima nel Lazio"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p><strong>LATINA<\/strong> &#8211; Il Lazio segna la sua terza vittima da West Nile. E&#8217; un 86enne deceduto al Santa Maria Goretti di Latina dove era stato tra i primi ricoverati, uno dei primi casi diagnosticati dagli infettivologi dell&#8217;ospedale di Latina e confermati dalle analisi eseguite allo Spallanzani. Il paziente, che aveva patologie pregresse, era ricoverato in terapia intensiva.<\/p>\n<p>Al momento <b>nel Lazio sono <\/b><b>44 i casi accertati<\/b>.<\/p>\n<p>Il presidente della Regione Francesco Rocca ha convocato per oggi una riunione operativa: &#8220;Nel pomeriggio\u00a0 &#8211; ha detto a margine di un evento che si \u00e8 svolto a Tor Vergata &#8211; valuteremo se adottare un\u2019ordinanza\u201d, annunciando anche &#8220;un milione di euro per sostenere i Comuni nelle operazioni di disinfestazione, soprattutto quelli che finora non hanno agito.\u201d<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>LATINA &#8211; Il Lazio segna la sua terza vittima da West Nile. E&#8217; un 86enne deceduto al Santa Maria Goretti di Latina dove era stato tra i primi ricoverati, uno dei primi casi diagnosticati dagli infettivologi dell&#8217;ospedale di Latina e confermati dalle analisi eseguite allo Spallanzani. Il paziente, che aveva patologie pregresse, era ricoverato in [&hellip;]<\/p>\n","protected":false},"author":62,"featured_media":338097,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[7,2428],"tags":[],"class_list":["post-382340","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cronaca","category-primo-piano"],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/382340","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/users\/62"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/comments?post=382340"}],"version-history":[{"count":4,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/382340\/revisions"}],"predecessor-version":[{"id":382344,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/382340\/revisions\/382344"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/media\/338097"}],"wp:attachment":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/media?parent=382340"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/categories?post=382340"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/tags?post=382340"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}