{"id":382380,"date":"2025-07-29T19:04:58","date_gmt":"2025-07-29T17:04:58","guid":{"rendered":"https:\/\/www.radioluna.it\/news\/?p=382380"},"modified":"2025-07-30T07:56:52","modified_gmt":"2025-07-30T05:56:52","slug":"latina-prepara-la-seconda-maratona-di-lettura-in-memoria-di-antonio-pennacchi-si-legge-palude","status":"publish","type":"post","link":"https:\/\/www.radioluna.it\/news\/2025\/07\/latina-prepara-la-seconda-maratona-di-lettura-in-memoria-di-antonio-pennacchi-si-legge-palude\/","title":{"rendered":"Latina prepara la seconda maratona di lettura in memoria di Antonio Pennacchi: si legge &#8220;Palude&#8221;"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p style=\"text-align: justify;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-382402 alignleft\" src=\"https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2025\/07\/Locandina-evento-1.jpeg\" alt=\"\" width=\"317\" height=\"452\" srcset=\"https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2025\/07\/Locandina-evento-1.jpeg 1120w, https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2025\/07\/Locandina-evento-1-768x1097.jpeg 768w, https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2025\/07\/Locandina-evento-1-1075x1536.jpeg 1075w\" sizes=\"auto, (max-width: 317px) 100vw, 317px\" \/>LATINA<\/strong> &#8211;\u00a0A quattro anni dalla scomparsa di Antonio Pennacchi, Premio Strega 2010 con Canale Mussolini, la citt\u00e0 di Latina lo ricorda con un doppio appuntamento: la presentazione ufficiale dell\u2019Associazione Amici di Antonio Pennacchi e la seconda edizione della maratona di lettura dedicata all\u2019autore pontino.<\/p>\n<p style=\"text-align: justify;\">L\u2019evento, organizzato in collaborazione con il Comune di Latina, si terr\u00e0 sabato 2 agosto a partire dalle ore 20.30 nell&#8217;Arena Cambellotti. Dopo il grande successo dello scorso anno, con la maratona dedicata a Canale Mussolini, protagoniste saranno le pagine di Palude, il secondo romanzo di Pennacchi (1995) dopo Mammuth (1994).<\/p>\n<p style=\"text-align: justify;\">Nel corso della serata sar\u00e0 ufficialmente presentata l\u2019Associazione Amici di Antonio Pennacchi, nata con l\u2019obiettivo di promuovere, custodire e diffondere l\u2019opera e il pensiero dello scrittore. La Presidenza Onoraria \u00e8 stata conferita a Ivana Busatto, moglie dello scrittore.<\/p>\n<p style=\"text-align: justify;\">Ospiti della serata saranno Giuseppe Iannaccone, Presidente del Centro per il Libro e la Lettura e curatore del Meridiano Mondadori dedicato a Pennacchi;\u00a0 e poi i docenti universitari Rino Caputo,\u00a0 Ugo Fracassa, Roberta Colombi e Fabrizio Miliucci; la scrittrice Barbara Alberti, l&#8217;attrice Gioia Battista e Cristian Ferrari, imprenditore e figlio di Palude. Parteciperanno a distanza con contributi video, l&#8217;attore e autore teatrale Andrea Pennacchi e lo scrittore Paolo Nori.<\/p>\n<p style=\"text-align: justify;\">LA SERATA &#8211; &#8220;La serata\u00a0 &#8211; spiegano in una nota gli organizzatori &#8211; si aprir\u00e0 con una prima fase in cui gli ospiti interverranno con aneddoti e riflessioni sull\u2019opera e sulla figura di Antonio Pennacchi. Gli interventi saranno intervallati da contributi video e audio, accompagnati da un loop fotografico che restituir\u00e0 momenti di vita, luoghi e volti legati alla biografia dello scrittore, con particolare attenzione al mondo della fabbrica che fa da sfondo a Palude, seconda opera di Pennacchi e chiave d\u2019ingresso alla sua poetica narrativa. A seguire, prender\u00e0 il via la vera e propria maratona di lettura: la lettura integrale di Palude, in cui si alterneranno sul palco tutte le cittadine e i cittadini che vorranno rendere omaggio allo scrittore leggendo un brano a scelta. Un momento collettivo di partecipazione e memoria, aperto a tutte e tutti, per continuare a dare voce a una storia che appartiene profondamente al territorio&#8221;.<\/p>\n<p style=\"text-align: justify;\">La conclusione della manifestazione sar\u00e0 al pontile di Capo Portiere, al termine del viale che porta il nome di Antonio Pennacchi: &#8220;Un ideale abbraccio tra la citt\u00e0, il mare e la memoria&#8221;.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>LATINA &#8211;\u00a0A quattro anni dalla scomparsa di Antonio Pennacchi, Premio Strega 2010 con Canale Mussolini, la citt\u00e0 di Latina lo ricorda con un doppio appuntamento: la presentazione ufficiale dell\u2019Associazione Amici di Antonio Pennacchi e la seconda edizione della maratona di lettura dedicata all\u2019autore pontino. L\u2019evento, organizzato in collaborazione con il Comune di Latina, si terr\u00e0 [&hellip;]<\/p>\n","protected":false},"author":62,"featured_media":382381,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16,2424],"tags":[],"class_list":["post-382380","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-appuntamenti","category-i-nostri-libri"],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/382380","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/users\/62"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/comments?post=382380"}],"version-history":[{"count":3,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/382380\/revisions"}],"predecessor-version":[{"id":382404,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/382380\/revisions\/382404"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/media\/382381"}],"wp:attachment":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/media?parent=382380"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/categories?post=382380"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/tags?post=382380"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}