{"id":382725,"date":"2025-08-02T16:08:39","date_gmt":"2025-08-02T14:08:39","guid":{"rendered":"https:\/\/www.radioluna.it\/news\/?p=382725"},"modified":"2025-08-02T16:08:39","modified_gmt":"2025-08-02T14:08:39","slug":"ponza-i-carabinieri-insistono-con-i-controlli-perquisizioni-e-sequestro-di-droga","status":"publish","type":"post","link":"https:\/\/www.radioluna.it\/news\/2025\/08\/ponza-i-carabinieri-insistono-con-i-controlli-perquisizioni-e-sequestro-di-droga\/","title":{"rendered":"Ponza, i carabinieri insistono con i controlli: perquisizioni e sequestro di droga"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p style=\"text-align: justify;\">Nelle giornata di ieri, i Carabinieri della Stazione di Ponza, unitamente ai militari del Nucleo Operativo e Radiomobile &#8211; Sezione Operativa della Compagnia di Formia, al personale del Battello CC40 e del Nucleo Cinofili di Roma Ponte Galeria, hanno eseguito un servizio straordinario di controllo del territorio sulla fascia costiera dell\u2019isola finalizzato alla prevenzione della criminalit\u00e0 comune e dell\u2019attivit\u00e0 di spaccio, garantendo al tempo stesso maggiore sicurezza alla circolazione stradale, con particolare riferimento alle zone della \u201cmovida\u201d, maggiormente frequentate e caratterizzate dalla presenza di diversi luoghi di aggregazione. Nello specifico sono stati predisposti servizi di pattugliamento, nel corso dei quali sono stati sottoposti a controlli: 1 veicolo, identificate 63 persone di cui 10 gravati da precedenti di polizia, 2 esercizi commerciali ed effettuate 3 perquisizioni personali di cui due con esito positivo. Nel medesimo contesto, i Carabinieri hanno deferito alle competenti Autorit\u00e0 Amministrative una donna di 29 anni e un ragazzo di 21 anni entrambi residenti a Roma, residente poich\u00e9 trovati in possesso rispettivamente di 5 grammi di sostanza stupefacente di tipo \u201chashish\u201d e 4,5 grammi di sostanza stupefacente di tipo \u201cmarijuana\u201d.<br \/>\nI Carabinieri hanno inoltre effettuato un controllo presso un\u2019attivit\u00e0 di noleggio natanti, sanzionando amministrativamente il titolare poich\u00e8 esercitava attivit\u00e0 di manipolazione alimenti senza aver presentato la prevista notifica all\u2019Autori\u00e0 competente per 3.000 euro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nelle giornata di ieri, i Carabinieri della Stazione di Ponza, unitamente ai militari del Nucleo Operativo e Radiomobile &#8211; Sezione Operativa della Compagnia di Formia, al personale del Battello CC40 e del Nucleo Cinofili di Roma Ponte Galeria, hanno eseguito un servizio straordinario di controllo del territorio sulla fascia costiera dell\u2019isola finalizzato alla prevenzione della [&hellip;]<\/p>\n","protected":false},"author":5443,"featured_media":382726,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[7,2428],"tags":[],"class_list":["post-382725","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cronaca","category-primo-piano"],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/382725","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/users\/5443"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/comments?post=382725"}],"version-history":[{"count":1,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/382725\/revisions"}],"predecessor-version":[{"id":382728,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/382725\/revisions\/382728"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/media\/382726"}],"wp:attachment":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/media?parent=382725"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/categories?post=382725"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/tags?post=382725"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}