{"id":382788,"date":"2025-08-04T07:02:10","date_gmt":"2025-08-04T05:02:10","guid":{"rendered":"https:\/\/www.radioluna.it\/news\/?p=382788"},"modified":"2025-08-04T07:02:10","modified_gmt":"2025-08-04T05:02:10","slug":"fabio-rampelli-ospite-alla-serata-di-chiusura-del-ciclo-di-talk-a-better-tomorrow","status":"publish","type":"post","link":"https:\/\/www.radioluna.it\/news\/2025\/08\/fabio-rampelli-ospite-alla-serata-di-chiusura-del-ciclo-di-talk-a-better-tomorrow\/","title":{"rendered":"Fabio Rampelli ospite alla serata di chiusura del ciclo di talk \u201cA Better Tomorrow\u201d"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p style=\"text-align: justify;\"><strong>SAN FELICE CIRCEO<\/strong> &#8211; Si conclude stasera, luned\u00ec 4 agosto alle ore 21.30, il ciclo di incontri estivi \u201cA Better Tomorrow\u201d, ideato dall\u2019agenzia di comunicazione Cenacoli in collaborazione con BAT Italia, con l\u2019obiettivo di promuovere il dialogo tra cittadini, istituzioni e imprese su temi di attualit\u00e0 e impatto locale. L\u2019evento finale, ospitato sulla terrazza panoramica di Vigna la Corte a San Felice Circeo, vedr\u00e0 protagonisti l\u2019on. Fabio Rampelli, vicepresidente della Camera dei Deputati, e Tommaso Cerno, direttore de Il Tempo, nell\u2019incontro \u201cDentro il motore della democrazia: dai retroscena all\u2019azione\u201d.<\/p>\n<p style=\"text-align: justify;\">Nel corso dell\u2019estate \u2018A Better Tomorrow\u2019 ha affrontato argomenti centrali come la sostenibilit\u00e0 ambientale, l\u2019effetto dei dazi statunitensi e le ricadute negative sulle economie locali, la prevenzione sanitaria \u2013 con un focus sulla diffusione del virus West Nile nel Lazio e la riduzione del danno da fumo, vista attraverso il complesso di studi scientifici e analisi della piattaforma Omni \u2013 coinvolgendo centinaia di persone che hanno affollato il salotto buono del Circeo che si affaccia sul golfo pontino.<\/p>\n<p style=\"text-align: justify;\">\u201cCon questa serata chiudiamo un percorso fatto di partecipazione \u2013 commenta Livio Buffo, CEO di Cenacoli \u2013 Abbiamo discusso temi nazionali, proiettandoli anche sul piano locale, offrendo uno spazio di dialogo reale tra cittadini, amministratori e mondo imprenditoriale.\u201d<\/p>\n<p style=\"text-align: justify;\">Durante le giornate di \u2018A Better Tomorrow\u2019 non sono mancati eventi collaterali, tra cui la campagna di sensibilizzazione ambientale \u201cPiccoli Gesti, Grandi Crimini\u201d promossa da Marevivo, che ha raccolto interesse e partecipazione sul lungomare sanfeliciano.<\/p>\n<p style=\"text-align: justify;\">\u201cA sei anni dal progetto pilota, \u2013 spiega Andrea Di Paolo, vicepresidente di BAT Italia \u2013 possiamo dire che, grazie a queste campagne la gente si \u00e8 interessata al tema del littering, sviluppando una coscienza su questoargomento che si \u00e8 tradotta in azioni quotidiane virtuose. \u2018A Better Tomorrow\u2019 \u00e8 uno stile di vita che si realizza tramite queste iniziative e incontri come quelli del Circeo, dove c\u2019\u00e8 stato un dialogo vero fra cittadini e amministratori.\u201d<\/p>\n<p style=\"text-align: justify;\">La serata finale sar\u00e0 preceduta da una degustazione di vini locali (ore 21, Vigna la Corte) e dalla distribuzione di materiale informativo relativo alle ricerche in corso sulla presenza di vitigni autoctoni non ancora registrati nell\u2019area del Circeo. Una scoperta che, se confermata, potrebbe rappresentare una nuova risorsa per l\u2019economia del territorio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SAN FELICE CIRCEO &#8211; Si conclude stasera, luned\u00ec 4 agosto alle ore 21.30, il ciclo di incontri estivi \u201cA Better Tomorrow\u201d, ideato dall\u2019agenzia di comunicazione Cenacoli in collaborazione con BAT Italia, con l\u2019obiettivo di promuovere il dialogo tra cittadini, istituzioni e imprese su temi di attualit\u00e0 e impatto locale. L\u2019evento finale, ospitato sulla terrazza panoramica [&hellip;]<\/p>\n","protected":false},"author":60,"featured_media":382789,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16,734],"tags":[],"class_list":["post-382788","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-appuntamenti","category-evidenza"],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/382788","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/users\/60"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/comments?post=382788"}],"version-history":[{"count":1,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/382788\/revisions"}],"predecessor-version":[{"id":382790,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/382788\/revisions\/382790"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/media\/382789"}],"wp:attachment":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/media?parent=382788"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/categories?post=382788"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/tags?post=382788"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}