{"id":382899,"date":"2025-08-05T14:14:44","date_gmt":"2025-08-05T12:14:44","guid":{"rendered":"https:\/\/www.radioluna.it\/news\/?p=382899"},"modified":"2025-08-06T07:32:41","modified_gmt":"2025-08-06T05:32:41","slug":"sabaudia-scavalca-la-recinzione-minacciando-ex-moglie-e-figli-arrestato","status":"publish","type":"post","link":"https:\/\/www.radioluna.it\/news\/2025\/08\/sabaudia-scavalca-la-recinzione-minacciando-ex-moglie-e-figli-arrestato\/","title":{"rendered":"Sabaudia, scavalca la recinzione minacciando ex moglie e figli: arrestato"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p style=\"text-align: justify;\"><strong>SABAUDIA<\/strong> &#8211; Sorpreso a scavalcare la recinzione dell&#8217;abitazione della ex moglie, minacciando lei e i figli di morte, \u00e8 stato arrestato in flagranza di reato un cittadino indiano di 45 anni in Italia senza fissa dimora, gi\u00e0 noto alle forze di polizia. I carabinieri intervenuti su richiesta della donna impaurita da quanto stava accadendo, hanno bloccato l&#8217;aggressore con l&#8217;accusa i maltrattamenti in famiglia e atti persecutori e lo hanno portato nel carcere di Latina dove resta in attesa dell&#8217;interrogatorio di convalida da parte del giudice.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SABAUDIA &#8211; Sorpreso a scavalcare la recinzione dell&#8217;abitazione della ex moglie, minacciando lei e i figli di morte, \u00e8 stato arrestato in flagranza di reato un cittadino indiano di 45 anni in Italia senza fissa dimora, gi\u00e0 noto alle forze di polizia. I carabinieri intervenuti su richiesta della donna impaurita da quanto stava accadendo, hanno [&hellip;]<\/p>\n","protected":false},"author":62,"featured_media":382900,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[7,2428],"tags":[],"class_list":["post-382899","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cronaca","category-primo-piano"],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/382899","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/users\/62"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/comments?post=382899"}],"version-history":[{"count":1,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/382899\/revisions"}],"predecessor-version":[{"id":382901,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/382899\/revisions\/382901"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/media\/382900"}],"wp:attachment":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/media?parent=382899"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/categories?post=382899"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/tags?post=382899"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}