{"id":382929,"date":"2025-08-05T19:26:32","date_gmt":"2025-08-05T17:26:32","guid":{"rendered":"https:\/\/www.radioluna.it\/news\/?p=382929"},"modified":"2025-08-05T19:26:32","modified_gmt":"2025-08-05T17:26:32","slug":"borgo-grappa-in-festa-fino-al-10-agosto-balli-musica-e-buon-cibo","status":"publish","type":"post","link":"https:\/\/www.radioluna.it\/news\/2025\/08\/borgo-grappa-in-festa-fino-al-10-agosto-balli-musica-e-buon-cibo\/","title":{"rendered":"Borgo Grappa in Festa: fino al 10 agosto balli, musica e buon cibo"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-382931 alignleft\" src=\"https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2025\/08\/PHOTO-2025-07-17-14-37-15-1.jpg\" alt=\"\" width=\"209\" height=\"299\" srcset=\"https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2025\/08\/PHOTO-2025-07-17-14-37-15-1.jpg 896w, https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2025\/08\/PHOTO-2025-07-17-14-37-15-1-768x1097.jpg 768w\" sizes=\"auto, (max-width: 209px) 100vw, 209px\" \/><strong>LATINA &#8211; <\/strong>\u00a0Entra nel vivo \u201cBorgo Grappa In Festa\u201d, la manifestazione che ha preso il via il primo agosto, prosegue organizzata dall\u2019associazione \u201cAmici del Borgo\u201d \u2013 Comitato di Borgo Grappa, in collaborazione con Opes Latina, Proloco Borgo Grappa e Centro Anziani di Borgo Grappa.<\/p>\n<p>Fino al 10 agosto, esibizioni di ballo, orchestre live, concerti dance &#8217;80, &#8217;90 e Duemila, dj set, concerti jazz, mostre ed esposizioni, stand gastronomici, e un\u2019area per bambini per la seconda edizione.\u00a0 Il programma prevede ogni sera divertimento per tutti e un piatto speciale da gustare nell\u2019area ristoro.<\/p>\n<p>L\u2019appuntamento nel cuore della frazione di Latina nell\u2019area del Monumento ai Caduti.<\/p>\n<p>L\u2019evento \u00e8 patrocinato dalla Regione Lazio, dalla Provincia di Latina e dal Comune di Latina e rientra nell&#8217;ambito delle iniziative che promuovono la riqualificazione del Monumento ai Caduti del borgo.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>LATINA &#8211; \u00a0Entra nel vivo \u201cBorgo Grappa In Festa\u201d, la manifestazione che ha preso il via il primo agosto, prosegue organizzata dall\u2019associazione \u201cAmici del Borgo\u201d \u2013 Comitato di Borgo Grappa, in collaborazione con Opes Latina, Proloco Borgo Grappa e Centro Anziani di Borgo Grappa. Fino al 10 agosto, esibizioni di ballo, orchestre live, concerti dance [&hellip;]<\/p>\n","protected":false},"author":60,"featured_media":382930,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16,734],"tags":[],"class_list":["post-382929","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-appuntamenti","category-evidenza"],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/382929","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/users\/60"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/comments?post=382929"}],"version-history":[{"count":1,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/382929\/revisions"}],"predecessor-version":[{"id":382933,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/382929\/revisions\/382933"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/media\/382930"}],"wp:attachment":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/media?parent=382929"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/categories?post=382929"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/tags?post=382929"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}