{"id":382990,"date":"2025-08-06T11:17:02","date_gmt":"2025-08-06T09:17:02","guid":{"rendered":"https:\/\/www.radioluna.it\/news\/?p=382990"},"modified":"2025-08-06T11:17:02","modified_gmt":"2025-08-06T09:17:02","slug":"san-michele-arcangelo-al-via-la-festa-patronale-di-borgo-san-michele","status":"publish","type":"post","link":"https:\/\/www.radioluna.it\/news\/2025\/08\/san-michele-arcangelo-al-via-la-festa-patronale-di-borgo-san-michele\/","title":{"rendered":"San Michele Arcangelo, al via la Festa patronale di Borgo San Michele"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-382992 alignleft\" src=\"https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2025-08-06-at-10.40.06.jpeg\" alt=\"\" width=\"385\" height=\"539\" \/><strong>LATINA &#8211; <\/strong>Prende il via oggi, mercoled\u00ec 6 agosto, a Borgo San Michele, la festa patronale dedicata a San Michele Arcangelo, promossa dalla parrocchia locale. Un festeggiamento carico di significato nell&#8217;anno del Giubileo, come sottolinea nel suo invito &#8220;a festeggiare e gioire insieme&#8221;, il parroco Don Wissam El Haddad ringraziando i residenti della frazione &#8220;per l&#8217;accoglienza calorosa ricevuta&#8221; da quella che definisce &#8220;una comunit\u00e0 viva, attenta e fraterna&#8221;.<\/p>\n<p style=\"text-align: justify;\">Il calendario \u00e8 fitto e accompagner\u00e0, residenti e non, fino al 10 agosto, tra musica e gastronomia, balli e giochi per bambini.<\/p>\n<p style=\"text-align: justify;\">Mercoled\u00ec 6 agosto l&#8217;inaugurazione alle 20: si balla la Zumba, a seguire cena insieme con il piatto del giorno, poi alle 21:00 lo spettacolo musicale con gli Agrodolce.<\/p>\n<p style=\"text-align: justify;\">Gioved\u00ec 7 agosto alle 20:30 e fino alle 21 una dimostrazione di pilates, poi dopo l&#8217;appuntamento con la cucina, alle 21 lo spettacolo musicale della band\u00a0 &#8220;Sempre musica italiana&#8221;.<\/p>\n<p style=\"text-align: justify;\">Venerd\u00ec 8 agosto protagonisti alle 21 i musicisti della\u00a0 &#8220;Banda del cuore&#8221;. Il concerto sar\u00e0 preceduto come sempre dal piatto del giorno.<\/p>\n<p style=\"text-align: justify;\">Sabato 9 agosto alle 21:00 lo spettacolo musicale de &#8220;Le stelle del liscio&#8221; con Claudio ed Elisa, che seguir\u00e0 l&#8217;appuntamento gastronomico con le casarecce delle cuoche nostrane.<\/p>\n<p>Domenica 10, il gran finale con lo spettacolo dei &#8220;Due note&#8221; che chiuder\u00e0 la manifestazione. Piatto del giorno: trionfo di gnocchi al rag\u00f9.<\/p>\n<p style=\"text-align: justify;\">Tutte le serate saranno accompagnate dall&#8217;animazione per i bambini in oratorio dalle 20:00 alle 22:30<\/p>\n","protected":false},"excerpt":{"rendered":"<p>LATINA &#8211; Prende il via oggi, mercoled\u00ec 6 agosto, a Borgo San Michele, la festa patronale dedicata a San Michele Arcangelo, promossa dalla parrocchia locale. Un festeggiamento carico di significato nell&#8217;anno del Giubileo, come sottolinea nel suo invito &#8220;a festeggiare e gioire insieme&#8221;, il parroco Don Wissam El Haddad ringraziando i residenti della frazione &#8220;per [&hellip;]<\/p>\n","protected":false},"author":60,"featured_media":382992,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16,734],"tags":[],"class_list":["post-382990","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-appuntamenti","category-evidenza"],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/382990","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/users\/60"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/comments?post=382990"}],"version-history":[{"count":1,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/382990\/revisions"}],"predecessor-version":[{"id":382993,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/382990\/revisions\/382993"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/media\/382992"}],"wp:attachment":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/media?parent=382990"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/categories?post=382990"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/tags?post=382990"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}