{"id":383856,"date":"2025-08-18T12:15:23","date_gmt":"2025-08-18T10:15:23","guid":{"rendered":"https:\/\/www.radioluna.it\/news\/?p=383856"},"modified":"2025-08-23T07:23:28","modified_gmt":"2025-08-23T05:23:28","slug":"aggredito-nel-parcheggio-ex-avir-gaeta-spegnera-le-luci-per-franco-perlino","status":"publish","type":"post","link":"https:\/\/www.radioluna.it\/news\/2025\/08\/aggredito-nel-parcheggio-ex-avir-gaeta-spegnera-le-luci-per-franco-perlino\/","title":{"rendered":"Aggredito nel parcheggio ex Avir, Gaeta spegner\u00e0 le luci per Franco Perlino"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p style=\"text-align: justify;\"><strong>GAETA<\/strong> &#8211; Si terranno oggi pomeriggio alle 16 presso la chiesa di Ges\u00f9 Maestro a Fonte Nuova le esequie dell\u201982enne Franco Perlino, l\u2019uomo deceduto gioved\u00ec scorso al \u201cDono Svizzero\u201d dopo essere stato spinto a terra durante una lite stradale avvenuta nell&#8217;area parcheggio ex Avir. Anche Gaeta ha previsto iniziative in ricordo dell&#8217;anziano che trascorreva sempre le sue vacanze nella citt\u00e0 del Golfo.<\/p>\n<p style=\"text-align: justify;\">Considerata la volont\u00e0 della famiglia e quella espressa da tanti cittadini, il 21 agosto alle 19 si terr\u00e0 una Messa in suffragio nella Parrocchia di San Paolo Apostolo in Gaeta. Al termine del rito religioso presso l\u2019 area parcheggio ex Avir ci sar\u00e0 un momento di raccoglimento. Poi,\u00a0 alle 20.30\u00a0 il Comune ha disposto di spegnere le luci di alcuni siti simbolo della citt\u00e0 e di altri luoghi per cinque minuti e invita anche privati e attivit\u00e0 commerciali a fare altrettanto. &#8220;Un&#8217;iniziativa simbolica\u00a0 &#8211; si legge in una nota del Comune &#8211;\u00a0 per dire basta, con determinazione e con forza, a ogni forma di violenza. Episodi come quello del povero Franco ma anche altre recenti e ugualmente gravi come le risse non devono pi\u00f9 accadere&#8221;.<\/p>\n<p style=\"text-align: justify;\">Ai funerali in programma oggi nel comune romano di residenza di Perlino parteciper\u00e0 anche il sindaco Leccese.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>GAETA &#8211; Si terranno oggi pomeriggio alle 16 presso la chiesa di Ges\u00f9 Maestro a Fonte Nuova le esequie dell\u201982enne Franco Perlino, l\u2019uomo deceduto gioved\u00ec scorso al \u201cDono Svizzero\u201d dopo essere stato spinto a terra durante una lite stradale avvenuta nell&#8217;area parcheggio ex Avir. Anche Gaeta ha previsto iniziative in ricordo dell&#8217;anziano che trascorreva sempre [&hellip;]<\/p>\n","protected":false},"author":62,"featured_media":383875,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[7],"tags":[],"class_list":["post-383856","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cronaca"],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/383856","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/users\/62"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/comments?post=383856"}],"version-history":[{"count":1,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/383856\/revisions"}],"predecessor-version":[{"id":383877,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/383856\/revisions\/383877"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/media\/383875"}],"wp:attachment":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/media?parent=383856"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/categories?post=383856"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/tags?post=383856"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}