{"id":384356,"date":"2025-08-25T07:21:55","date_gmt":"2025-08-25T05:21:55","guid":{"rendered":"https:\/\/www.radioluna.it\/news\/?p=384356"},"modified":"2025-08-25T12:05:32","modified_gmt":"2025-08-25T10:05:32","slug":"tragico-incidente-sulla-fondi-santanastasia-muore-un-ragazzo-di-lenola","status":"publish","type":"post","link":"https:\/\/www.radioluna.it\/news\/2025\/08\/tragico-incidente-sulla-fondi-santanastasia-muore-un-ragazzo-di-lenola\/","title":{"rendered":"Tragico incidente sulla Fondi Sant&#8217;Anastasia, muore un ragazzo di Lenola"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p style=\"text-align: justify;\"><strong>FONDI<\/strong> &#8211; E&#8217; un ragazzo di Lenola la vittima di un tragico incidente stradale che si \u00e8 verificato a Fondi nella tarda serata di sabato. Biagio Carroccia, 29 anni, viaggiava sulla sua moto che per ragioni da accertare si \u00e8 scontrata con una Fiat Panda che percorreva la Fondi-Sant&#8217;Anastasia nel senso di marcia opposto. All&#8217;interno della vettura una coppia originaria della Campania, marito e moglie di 76 e 70 anni rimasti entrambi feriti in maniera seria, ma non in pericolo di vita.<\/p>\n<p style=\"text-align: justify;\">L&#8217;impatto violento avvenuto ha fatto sbalzare il motociclista sull&#8217;asfalto a diversi metri di distanza, e subito dopo la sua moto ha preso fuoco. Sono stati vani i soccorsi prestati dai sanitari del 118 intervenuti sul posto con i carabinieri della tenenza di Fondi che hanno svolto i rilievi.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>FONDI &#8211; E&#8217; un ragazzo di Lenola la vittima di un tragico incidente stradale che si \u00e8 verificato a Fondi nella tarda serata di sabato. Biagio Carroccia, 29 anni, viaggiava sulla sua moto che per ragioni da accertare si \u00e8 scontrata con una Fiat Panda che percorreva la Fondi-Sant&#8217;Anastasia nel senso di marcia opposto. All&#8217;interno [&hellip;]<\/p>\n","protected":false},"author":60,"featured_media":383002,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[7,2428],"tags":[],"class_list":["post-384356","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cronaca","category-primo-piano"],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/384356","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/users\/60"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/comments?post=384356"}],"version-history":[{"count":1,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/384356\/revisions"}],"predecessor-version":[{"id":384357,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/384356\/revisions\/384357"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/media\/383002"}],"wp:attachment":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/media?parent=384356"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/categories?post=384356"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/tags?post=384356"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}