{"id":385383,"date":"2025-09-08T15:58:47","date_gmt":"2025-09-08T13:58:47","guid":{"rendered":"https:\/\/www.radioluna.it\/news\/?p=385383"},"modified":"2025-09-09T07:24:30","modified_gmt":"2025-09-09T05:24:30","slug":"latina-incendio-notturno-in-via-palestro-distrutta-unauto","status":"publish","type":"post","link":"https:\/\/www.radioluna.it\/news\/2025\/09\/latina-incendio-notturno-in-via-palestro-distrutta-unauto\/","title":{"rendered":"Latina, incendio notturno in via Palestro: distrutta un&#8217;auto"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p style=\"text-align: justify;\" data-start=\"103\" data-end=\"268\">Latina, auto in fiamme all\u2019alba in via Palestro. Un SUV parcheggiato a poca distanza dal centro e da piazza del Quadrato \u00e8 stato completamente distrutto dal fuoco.\u00a0Sono stati i residenti, svegliati dal rogo, a dare l\u2019allarme e a chiamare i vigili del fuoco, che sono intervenuti rapidamente riuscendo a spegnere le fiamme e a mettere in sicurezza l\u2019area.\u00a0Terminate le operazioni di spegnimento, sono scattate le indagini della Questura per risalire alle cause dell\u2019incendio. Non si esclude la pista dolosa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Latina, auto in fiamme all\u2019alba in via Palestro. Un SUV parcheggiato a poca distanza dal centro e da piazza del Quadrato \u00e8 stato completamente distrutto dal fuoco.\u00a0Sono stati i residenti, svegliati dal rogo, a dare l\u2019allarme e a chiamare i vigili del fuoco, che sono intervenuti rapidamente riuscendo a spegnere le fiamme e a mettere [&hellip;]<\/p>\n","protected":false},"author":5443,"featured_media":385384,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[7],"tags":[],"class_list":["post-385383","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cronaca"],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/385383","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/users\/5443"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/comments?post=385383"}],"version-history":[{"count":1,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/385383\/revisions"}],"predecessor-version":[{"id":385385,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/385383\/revisions\/385385"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/media\/385384"}],"wp:attachment":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/media?parent=385383"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/categories?post=385383"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/tags?post=385383"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}