{"id":385503,"date":"2025-09-10T14:31:23","date_gmt":"2025-09-10T12:31:23","guid":{"rendered":"https:\/\/www.radioluna.it\/news\/?p=385503"},"modified":"2025-09-11T09:52:53","modified_gmt":"2025-09-11T07:52:53","slug":"latin-comitato-per-lordine-e-la-sicurezza-sulle-due-bombe-ciaramella-intensificata-la-vigilanza-e-servizi-straordinari-a-latina","status":"publish","type":"post","link":"https:\/\/www.radioluna.it\/news\/2025\/09\/latin-comitato-per-lordine-e-la-sicurezza-sulle-due-bombe-ciaramella-intensificata-la-vigilanza-e-servizi-straordinari-a-latina\/","title":{"rendered":"Latina, comitato per l&#8217;ordine e la sicurezza sulle due bombe, Ciaramella: &#8220;Intensificata la vigilanza e servizi straordinari&#8221;"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p style=\"text-align: justify;\"><strong>LATINA &#8211;<\/strong>\u00a0 Si \u00e8 tenuto questa mattina il Comitato provinciale per l&#8217;ordine e la sicurezza pubblica presieduto dalla prefetta Vittoria Ciaramella dopo le esplosioni dei due ordini avvenute all&#8217;alba di domenica in Via Guido Rossa a Latina e nella notte tra domenica e luned\u00ec in Via Darsena.<\/p>\n<p style=\"text-align: justify;\">&#8220;Sono gi\u00e0 stati intensificati servizi di vigilanza e di controllo del territorio da parte delle forze di polizia\u00a0 &#8211; sottolinea in una nota la Prefettura &#8211; in particolare nelle aree interessate dalle esplosioni. E&#8217; stata anche assicurata la massima attenzione della Prefettura per innalzare il livello di sicurezza percepita da parte della collettivit\u00e0&#8221;.<\/p>\n<p style=\"text-align: justify;\">Al tavolo \u00e8 stato deciso che saranno dunque effettuati nei prossimi giorni &#8220;servizi straordinari di controllo mirati e visibili con personale in divisa in borghese e pianificate operazioni interforze ad alto impatto che consentiranno\u00a0 &#8211; sottolinea la nota ufficiale &#8211; di offrire una risposta pronta ed efficace alle esigenze di sicurezza della comunit\u00e0 locale&#8221;.<\/p>\n<p style=\"text-align: justify;\">Saranno anche avviate verifiche sugli appartamenti del complesso di via Guido Rossa dove domenica all\u2019alba un potente ordigno ha causato danni al civico 10. L\u2019obiettivo \u00e8 &#8220;accertare eventuali situazioni di occupazione abusiva o altre irregolarit\u00e0\u201d, spiega la sindaca di Latina Matilde Celentano che ha partecipato alla riunione provando a rassicurare la cittadinanza: \u201cSi tratta di episodi che hanno inevitabilmente generato forte preoccupazione tra i cittadini. Voglio tuttavia rassicurare la popolazione: sono in corso accurate indagini da parte delle forze dell\u2019ordine, alle quali va tutta la mia fiducia\u201d, aggiunge.<\/p>\n<p style=\"text-align: justify;\">Sulle indagini in corso vige stretto riserbo, ma filtra un certo ottimismo sulla possibilit\u00e0 che si arrivi presto alla cattura dei responsabili dei due attentati. Le indagini dei carabinieri, coordinate dalla Procura di Latina, su quella che \u00e8 stata classificata come una guerra per il controllo delle piazze di spaccio, proseguono anche per chiarire che cosa l&#8217;abbia innescata.<\/p>\n<p style=\"text-align: justify;\">All&#8217;incontro per fare il punto c&#8217;erano il questore Fausto Vinci e i comandanti provinciali di Carabinieri e Guardia di finanza, Cristian Angelillo e Giovanni Marchetti.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>LATINA &#8211;\u00a0 Si \u00e8 tenuto questa mattina il Comitato provinciale per l&#8217;ordine e la sicurezza pubblica presieduto dalla prefetta Vittoria Ciaramella dopo le esplosioni dei due ordini avvenute all&#8217;alba di domenica in Via Guido Rossa a Latina e nella notte tra domenica e luned\u00ec in Via Darsena. &#8220;Sono gi\u00e0 stati intensificati servizi di vigilanza e [&hellip;]<\/p>\n","protected":false},"author":62,"featured_media":358229,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[7,2428],"tags":[],"class_list":["post-385503","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cronaca","category-primo-piano"],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/385503","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/users\/62"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/comments?post=385503"}],"version-history":[{"count":5,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/385503\/revisions"}],"predecessor-version":[{"id":385541,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/385503\/revisions\/385541"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/media\/358229"}],"wp:attachment":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/media?parent=385503"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/categories?post=385503"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/tags?post=385503"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}