{"id":385736,"date":"2025-09-13T08:15:35","date_gmt":"2025-09-13T06:15:35","guid":{"rendered":"https:\/\/www.radioluna.it\/news\/?p=385736"},"modified":"2025-09-13T15:39:58","modified_gmt":"2025-09-13T13:39:58","slug":"altra-esplosione-nella-notta-a-latina-bomba-carta-piazzata-sotto-una-smart-sempre-ai-palazzi-arlecchino","status":"publish","type":"post","link":"https:\/\/www.radioluna.it\/news\/2025\/09\/altra-esplosione-nella-notta-a-latina-bomba-carta-piazzata-sotto-una-smart-sempre-ai-palazzi-arlecchino\/","title":{"rendered":"Altra esplosione nella notta a Latina, bomba carta piazzata sotto una Smart sempre in via Guido Rossa"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p>A Latina non si arresta la guerra per il controllo dello spaccio. Stanotte altra esplosione, altra bomba carta, ma sempre la stessa  zona, ovvero quella teatro della prima esplosione domenica mattina, via Guido Rossa, stavolta \u00e8 accaduto nelle palazzine di fronte. Chiss\u00e0 se questa volta per\u00f2 ci sia stato un errore, perch\u00e9 la bomba carta \u00e8 stata piazzata sull&#8217;auto di una donna li residente, ma che appare totalmente estranea a qualsiasi legame con la malavita. Sul posto i carabinieri e i vigili del fuoco.    <\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Latina non si arresta la guerra per il controllo dello spaccio. Stanotte altra esplosione, altra bomba carta, ma sempre la stessa zona, ovvero quella teatro della prima esplosione domenica mattina, via Guido Rossa, stavolta \u00e8 accaduto nelle palazzine di fronte. Chiss\u00e0 se questa volta per\u00f2 ci sia stato un errore, perch\u00e9 la bomba carta [&hellip;]<\/p>\n","protected":false},"author":5444,"featured_media":382832,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[7,2428],"tags":[],"class_list":["post-385736","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cronaca","category-primo-piano"],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/385736","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/users\/5444"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/comments?post=385736"}],"version-history":[{"count":3,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/385736\/revisions"}],"predecessor-version":[{"id":385742,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/385736\/revisions\/385742"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/media\/382832"}],"wp:attachment":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/media?parent=385736"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/categories?post=385736"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/tags?post=385736"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}