{"id":385822,"date":"2025-09-15T06:41:14","date_gmt":"2025-09-15T04:41:14","guid":{"rendered":"https:\/\/www.radioluna.it\/news\/?p=385822"},"modified":"2025-09-15T12:27:56","modified_gmt":"2025-09-15T10:27:56","slug":"farmaci-ad-azione-stupefacente-acquistati-con-documenti-contraffatti-e-false-ricette-9-arresti","status":"publish","type":"post","link":"https:\/\/www.radioluna.it\/news\/2025\/09\/farmaci-ad-azione-stupefacente-acquistati-con-documenti-contraffatti-e-false-ricette-9-arresti\/","title":{"rendered":"Farmaci ad azione stupefacente acquistati con documenti contraffatti e false ricette: 9 arresti"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p style=\"text-align: justify;\"><strong>LATINA &#8211;<\/strong> Un sistema di approvvigionamento illecito di farmaci ad azione stupefacente, mediante l\u2019uso di ricette mediche false e documenti di identit\u00e0 contraffatti \u00e8 stato scoperto dai carabinieri del Nas di Latina e ha portato ad un&#8217;operazione scattata all&#8217;alba di oggi. <a href=\"https:\/\/www.radioluna.it\/news\/2025\/09\/il-mercato-nero-dei-super-antidolorifici-a-cisterna-e-sermoneta-ogni-pasticca-rivenduta-a15-euro-nove-arresti\/\">AGGIORNAMENTO<\/a> Sotto il coordinamento costante della Procura\u00a0 della Repubblica i militari del Nucleo Tutela della Salute guidati dal comandante Felice Egidio hanno dato esecuzione a nove ordinanze di custodia cautelare arrivate al termine di una lunga e complessa attivit\u00e0 investigativa che ha evidenziato anche un&#8217; attivit\u00e0 parallele di spaccio di sostanze stupefacenti.<br \/>\nSono attualmente impiegati oltre 50 militari del Comando Carabinieri per la Tutela della Salute, del Comando Provinciale di Latina, del Nucleo Elicotteri di Pratica di Mare e delle unit\u00e0 cinofile di Santa Maria di Galeria, per finalizzare i 9 provvedimenti restrittivi della libert\u00e0 personale emessi dal Gip del Tribunale di Latina.<\/p>\n<p style=\"text-align: justify;\">A breve si conosceranno i dettagli.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>LATINA &#8211; Un sistema di approvvigionamento illecito di farmaci ad azione stupefacente, mediante l\u2019uso di ricette mediche false e documenti di identit\u00e0 contraffatti \u00e8 stato scoperto dai carabinieri del Nas di Latina e ha portato ad un&#8217;operazione scattata all&#8217;alba di oggi. AGGIORNAMENTO Sotto il coordinamento costante della Procura\u00a0 della Repubblica i militari del Nucleo Tutela [&hellip;]<\/p>\n","protected":false},"author":62,"featured_media":383680,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[7,2428],"tags":[],"class_list":["post-385822","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cronaca","category-primo-piano"],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/385822","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/users\/62"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/comments?post=385822"}],"version-history":[{"count":3,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/385822\/revisions"}],"predecessor-version":[{"id":385863,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/385822\/revisions\/385863"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/media\/383680"}],"wp:attachment":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/media?parent=385822"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/categories?post=385822"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/tags?post=385822"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}