{"id":385977,"date":"2025-09-16T14:04:51","date_gmt":"2025-09-16T12:04:51","guid":{"rendered":"https:\/\/www.radioluna.it\/news\/?p=385977"},"modified":"2025-09-17T10:37:24","modified_gmt":"2025-09-17T08:37:24","slug":"pedofilia-papa-leone-xiv-espelle-alessandro-frateschi-senza-appello-non-e-piu-diacono-di-latina","status":"publish","type":"post","link":"https:\/\/www.radioluna.it\/news\/2025\/09\/pedofilia-papa-leone-xiv-espelle-alessandro-frateschi-senza-appello-non-e-piu-diacono-di-latina\/","title":{"rendered":"Pedofilia, Papa Leone XIV espelle Alessandro Frateschi senza appello: \u00e8 fuori dallo stato clericale"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p style=\"text-align: justify;\"><strong>LATINA<\/strong> &#8211; Condannato per pedofilia, Alessandro Frateschi, l&#8217;uomo di Terracina che insegnava religione a scuola, non \u00e8 pi\u00f9 diacono permanente della Diocesi di Latina. Il decreto di dimissione dallo stato clericale \u00e8 stato emesso per decisione diretta di papa Leone XIV e\u00a0 notificato questa mattina al destinatario nel carcere di Latina dove si trova detenuto dopo la condanna a 12 anni di reclusione per violenza sessuale su minore. Si tratta di un decreto di condanna non appellabile.<\/p>\n<p style=\"text-align: justify;\"><strong>DELICTA GRAVIORA<\/strong> &#8211; Il procedimento canonico \u00e8 stato istruito e curato dalla Sezione Disciplinare del Dicastero per la Dottrina della Fede, cui compete il giudizio circa i reati annoverati tra i cosiddetti Delicta graviora, come quelli \u00abcontro il sesto comandamento del Decalogo commesso da un chierico con un minore di diciotto anni\u00bb.\u00a0 Nel caso specifico di Alessandro Frateschi, il Dicastero per la Dottrina della Fede vista la gravit\u00e0 e il manifesto compimento dei delitti da lui commessi ha deciso di deferire la decisione direttamente al Sommo Pontefice.<\/p>\n<p style=\"text-align: justify;\"><strong>GLI EFFETTI<\/strong> &#8211; Nel corso della notifica, \u00e8 stato spiegato a Frateschi che tra l\u2019altro non potr\u00e0 pi\u00f9 parlare in nome della Chiesa, non potr\u00e0 tenere omelie, non potr\u00e0 pi\u00f9 assumere incarichi di alcun genere nei Seminari o nelle Parrocchie, non potr\u00e0 pi\u00f9 insegnare materie teologiche nelle istituzioni scolastiche e accademiche dipendenti dall\u2019Autorit\u00e0 ecclesiastica, non potr\u00e0 pi\u00f9 insegnare materie teologiche o la religione cattolica nelle scuole non dipendenti dall\u2019Autorit\u00e0 ecclesiastica.<\/p>\n<p style=\"text-align: justify;\"><strong>PRIMA L&#8217;ALLONTANAMENTO\u00a0<\/strong> &#8211; Come previsto dalle attuali norme canoniche, il vescovo di Latina-Terracina-Sezze-Priverno Mariano Crociata aveva rimesso la posizione di Alessandro Frateschi al competente Dicastero subito dopo che gli era stato segnalato il caso, ma aveva gi\u00e0 preso provvedimenti. Il 30 gennaio 2023, dopo aver appreso che il Liceo Majorana di Latina chiedeva la nomina di un nuovo insegnante di religione dopo le denunce arrivate dalle famiglie di alcuni alunni, Crociata aveva ricevuto le dimissioni dall\u2019incarico di Frateschi al quale aveva comunicato la revoca dell\u2019idoneit\u00e0 all\u2019insegnamento della religione cattolica, imponendogli l\u2019allontanamento cautelare dall\u2019esercizio del ministero diaconale.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">\n","protected":false},"excerpt":{"rendered":"<p>LATINA &#8211; Condannato per pedofilia, Alessandro Frateschi, l&#8217;uomo di Terracina che insegnava religione a scuola, non \u00e8 pi\u00f9 diacono permanente della Diocesi di Latina. Il decreto di dimissione dallo stato clericale \u00e8 stato emesso per decisione diretta di papa Leone XIV e\u00a0 notificato questa mattina al destinatario nel carcere di Latina dove si trova detenuto [&hellip;]<\/p>\n","protected":false},"author":62,"featured_media":385978,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[7,2428],"tags":[],"class_list":["post-385977","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cronaca","category-primo-piano"],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/385977","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/users\/62"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/comments?post=385977"}],"version-history":[{"count":10,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/385977\/revisions"}],"predecessor-version":[{"id":385989,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/385977\/revisions\/385989"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/media\/385978"}],"wp:attachment":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/media?parent=385977"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/categories?post=385977"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/tags?post=385977"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}