{"id":386598,"date":"2025-09-24T17:40:55","date_gmt":"2025-09-24T15:40:55","guid":{"rendered":"https:\/\/www.radioluna.it\/news\/?p=386598"},"modified":"2025-09-25T08:59:21","modified_gmt":"2025-09-25T06:59:21","slug":"potenziamento-della-sicurezza-a-latina-in-arrivo-300-telecamere-e-una-control-room","status":"publish","type":"post","link":"https:\/\/www.radioluna.it\/news\/2025\/09\/potenziamento-della-sicurezza-a-latina-in-arrivo-300-telecamere-e-una-control-room\/","title":{"rendered":"Potenziamento della sicurezza a Latina, in arrivo 300 telecamere e una control room"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p style=\"text-align: justify;\" data-start=\"174\" data-end=\"597\">La Regione Lazio rafforza la sicurezza a Latina: oltre alle 300 telecamere gi\u00e0 annunciate, arriver\u00e0 anche una <strong data-start=\"284\" data-end=\"302\">\u201ccontrol room\u201d<\/strong> per gestire in tempo reale la mole di immagini e dati in ingresso. L\u2019annuncio \u00e8 stato dato dall\u2019assessore regionale alla Sicurezza, <strong data-start=\"435\" data-end=\"454\">Luisa Regimenti<\/strong>, al termine di un incontro con il sindaco <strong data-start=\"497\" data-end=\"518\">Matilde Celentano<\/strong>, per fare il punto sulla recente escalation criminale nel capoluogo pontino.<\/p>\n<p style=\"text-align: justify;\" data-start=\"599\" data-end=\"1086\">L&#8217;assessore ha tenuto a rassicurare sulla presenza e il supporto della Regione Lazio, affinch\u00e9 i cittadini possano vivere con tranquillit\u00e0 e senza paura per la loro incolumit\u00e0. Gli uffici tecnici sono gi\u00e0 al lavoro per predisporre l\u2019installazione delle nuove telecamere di videosorveglianza. Per processare tutti i dati e metterli in rete per il controllo del territorio le centrali operative saranno supportate dalla control room di sistema avanzato. In futuro, si valuter\u00e0 anche l&#8217;installazione di telecamere intelligenti di nuova generazione, che riconoscono l\u2019azione delittuosa. \u201cPorto la solidariet\u00e0 della Regione non solo con le parole ma anche con i fatti \u2013 ha detto Luisa Regimenti che ha spiegato le novit\u00e0 sulla sicurezza nel capoluogo:<\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-386598-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2025\/09\/sicurezza-regimenti.mp3?_=1\" \/><a href=\"https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2025\/09\/sicurezza-regimenti.mp3\">https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2025\/09\/sicurezza-regimenti.mp3<\/a><\/audio>\n<p style=\"text-align: justify;\" data-start=\"1088\" data-end=\"1460\">Il piano &#8220;telecamere&#8221; passa alla sua fase operativa ha sottolineato il sindaco Celentano:<\/p>\n<div class=\"html-div xdj266r x14z9mp xat24cr x1lziwak xexx8yu xyri2b x18d9i69 x1c1uobl\">\n<div class=\"html-div xdj266r x14z9mp xat24cr x1lziwak xexx8yu xyri2b x18d9i69 x1c1uobl\" dir=\"auto\" style=\"text-align: justify;\">\n<div class=\"html-div xdj266r x14z9mp xat24cr x1lziwak xexx8yu xyri2b x18d9i69 x1c1uobl\" data-ad-rendering-role=\"story_message\">\n<div id=\"_r_9bj_\" class=\"x1l90r2v x1iorvi4 x1g0dm76 xpdmqnj\" data-ad-comet-preview=\"message\" data-ad-preview=\"message\">\n<div class=\"x78zum5 xdt5ytf xz62fqu x16ldp7u\">\n<div class=\"xu06os2 x1ok221b\">\n<div class=\"html-div xdj266r x14z9mp xat24cr x1lziwak xexx8yu xyri2b x18d9i69 x1c1uobl\">\n<div class=\"x14z9mp xat24cr x1lziwak x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">\n<audio class=\"wp-audio-shortcode\" id=\"audio-386598-2\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2025\/09\/sicurezza-celentano.mp3?_=2\" \/><a href=\"https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2025\/09\/sicurezza-celentano.mp3\">https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2025\/09\/sicurezza-celentano.mp3<\/a><\/audio>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"_r_9bk_\" class=\"html-div xdj266r x14z9mp xat24cr x1lziwak xexx8yu xyri2b x18d9i69 x1c1uobl x1n2onr6\">\n<div class=\"html-div xdj266r x14z9mp xat24cr x1lziwak xexx8yu xyri2b x18d9i69 x1c1uobl x1n2onr6\">\n<div class=\"html-div xdj266r x14z9mp xat24cr x1lziwak xexx8yu xyri2b x18d9i69 x1c1uobl\">\n<div class=\"x1n2onr6\">\n<div class=\"x1n2onr6\">\n<div class=\"x6ikm8r x10wlt62 x10l6tqk\" style=\"text-align: justify;\"><\/div>\n<div class=\"x6ikm8r x10wlt62 x10l6tqk\" style=\"text-align: justify;\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Regione Lazio rafforza la sicurezza a Latina: oltre alle 300 telecamere gi\u00e0 annunciate, arriver\u00e0 anche una \u201ccontrol room\u201d per gestire in tempo reale la mole di immagini e dati in ingresso. L\u2019annuncio \u00e8 stato dato dall\u2019assessore regionale alla Sicurezza, Luisa Regimenti, al termine di un incontro con il sindaco Matilde Celentano, per fare il [&hellip;]<\/p>\n","protected":false},"author":5443,"featured_media":386599,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[7,2428],"tags":[],"class_list":["post-386598","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cronaca","category-primo-piano"],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/386598","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/users\/5443"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/comments?post=386598"}],"version-history":[{"count":1,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/386598\/revisions"}],"predecessor-version":[{"id":386602,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/386598\/revisions\/386602"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/media\/386599"}],"wp:attachment":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/media?parent=386598"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/categories?post=386598"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/tags?post=386598"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}