{"id":386890,"date":"2025-09-29T08:22:32","date_gmt":"2025-09-29T06:22:32","guid":{"rendered":"https:\/\/www.radioluna.it\/news\/?p=386890"},"modified":"2025-09-30T14:03:34","modified_gmt":"2025-09-30T12:03:34","slug":"duplice-femminicidio-di-cisterna-e-il-giorno-del-verdetto-per-christian-sodano","status":"publish","type":"post","link":"https:\/\/www.radioluna.it\/news\/2025\/09\/duplice-femminicidio-di-cisterna-e-il-giorno-del-verdetto-per-christian-sodano\/","title":{"rendered":"Duplice femminicidio di Cisterna, \u00e8 il giorno del verdetto per Christian Sodano"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p style=\"text-align: justify;\"><strong>LATINA &#8211;<\/strong> E\u2019 il giorno del verdetto per il duplice femminicidio di Nicoletta Zomparelli e Rene\u00e9 Amato, le due donne uccise dal finanziere Christian Sodano nella loro abitazione di Cisterna dove lui era ospite di Desire\u00e9, figlia della prima e sorella della seconda. La ragazza voleva lasciarlo e il 13 febbraio dello scorso anno glielo aveva detto, scatenando una reazione sanguinaria. Si torna questa mattina in aula, in tribunale a Latina, per le repliche, poi la Corte D\u2019Assise presieduta si ritirer\u00e0 in camera di Consiglio per la decisione. L&#8217;accusa ha chiesto per Sodano il massimo della pena ritenendolo colpevole di omicidio premeditato aggravato dai motivi abbietti.<\/p>\n<p style=\"text-align: justify;\">Nel processo di primo grado, oltre ai familiari delle due vittime, si \u00e8 costituito parte civile anche il Comune di Cisterna.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>LATINA &#8211; E\u2019 il giorno del verdetto per il duplice femminicidio di Nicoletta Zomparelli e Rene\u00e9 Amato, le due donne uccise dal finanziere Christian Sodano nella loro abitazione di Cisterna dove lui era ospite di Desire\u00e9, figlia della prima e sorella della seconda. La ragazza voleva lasciarlo e il 13 febbraio dello scorso anno glielo [&hellip;]<\/p>\n","protected":false},"author":62,"featured_media":377751,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[7],"tags":[],"class_list":["post-386890","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cronaca"],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/386890","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/users\/62"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/comments?post=386890"}],"version-history":[{"count":1,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/386890\/revisions"}],"predecessor-version":[{"id":386891,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/386890\/revisions\/386891"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/media\/377751"}],"wp:attachment":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/media?parent=386890"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/categories?post=386890"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/tags?post=386890"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}