{"id":387037,"date":"2025-09-30T18:26:56","date_gmt":"2025-09-30T16:26:56","guid":{"rendered":"https:\/\/www.radioluna.it\/news\/?p=387037"},"modified":"2025-10-01T07:57:15","modified_gmt":"2025-10-01T05:57:15","slug":"sermoneta-si-lancia-contro-i-carabinieri-brandendo-una-falce-e-gridando-allah-akbar-arrestato","status":"publish","type":"post","link":"https:\/\/www.radioluna.it\/news\/2025\/09\/sermoneta-si-lancia-contro-i-carabinieri-brandendo-una-falce-e-gridando-allah-akbar-arrestato\/","title":{"rendered":"Sermoneta, si lancia contro i carabinieri brandendo una falce e gridando Allah Akbar: arrestato"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p style=\"text-align: justify;\"><strong>SERMONETA &#8211; <\/strong>Si aggirava nelle strade di borgata Carrara a Sermoneta in stato di forte agitazione, brandendo una falce e quando ha visto i carabinieri che erano stati chiamati dai residenti si \u00e8 lanciato contro di loro al grido di \u201cAllah Akbar\u201d ed altre frasi incomprensibili, tentando pi\u00f9 volte di colpire i militari con la lama. Immobilizzato, con non poche difficolt\u00e0, \u00e8 stato tratto in arresto un cittadino di nazionalit\u00e0 gambiana di 26 anni, per i reati di resistenza a pubblico ufficiale e porto di armi. Il ragazzo \u00e8 ora trattenuto nelle camere di sicurezza in attesa della convalida dell\u2019arresto che si terr\u00e0 nella giornata di domani con rito direttissimo. I fatti sono avvenuti nella tarda serata luned\u00ec.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SERMONETA &#8211; Si aggirava nelle strade di borgata Carrara a Sermoneta in stato di forte agitazione, brandendo una falce e quando ha visto i carabinieri che erano stati chiamati dai residenti si \u00e8 lanciato contro di loro al grido di \u201cAllah Akbar\u201d ed altre frasi incomprensibili, tentando pi\u00f9 volte di colpire i militari con la [&hellip;]<\/p>\n","protected":false},"author":62,"featured_media":387038,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[7,2428],"tags":[],"class_list":["post-387037","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cronaca","category-primo-piano"],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/387037","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/users\/62"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/comments?post=387037"}],"version-history":[{"count":1,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/387037\/revisions"}],"predecessor-version":[{"id":387039,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/387037\/revisions\/387039"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/media\/387038"}],"wp:attachment":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/media?parent=387037"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/categories?post=387037"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/tags?post=387037"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}