{"id":387136,"date":"2025-10-02T08:22:16","date_gmt":"2025-10-02T06:22:16","guid":{"rendered":"https:\/\/www.radioluna.it\/news\/?p=387136"},"modified":"2025-10-02T08:22:16","modified_gmt":"2025-10-02T06:22:16","slug":"i-quotidiani-di-latina-in-un-click-2-ottobre-2025","status":"publish","type":"post","link":"https:\/\/www.radioluna.it\/news\/2025\/10\/i-quotidiani-di-latina-in-un-click-2-ottobre-2025\/","title":{"rendered":"I quotidiani di Latina in un click &#8211; 2 ottobre 2025"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p style=\"text-align: justify;\"><strong>LATINA<\/strong> &#8211; Qui trovate Prima Pagina, in un file audio di pochi minuti, i titoli di Latina Editoriale Oggi e del Messaggero Latina.<\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-387136-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2025\/10\/TITOLI-1.mp3?_=1\" \/><a href=\"https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2025\/10\/TITOLI-1.mp3\">https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2025\/10\/TITOLI-1.mp3<\/a><\/audio>\n<div id=\"radio-4062228122\" class=\"radio-dopo-il-contenuto radio-entity-placement\"><a href=\"https:\/\/concessionari-suzuki.it\/bodema\/\" aria-label=\"Bodema 1200&#215;600 banner Suzuki_AX\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2025\/05\/Bodema-1200x600-banner-Suzuki_AX.jpg\" alt=\"\"  srcset=\"https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2025\/05\/Bodema-1200x600-banner-Suzuki_AX.jpg 1200w, https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2025\/05\/Bodema-1200x600-banner-Suzuki_AX-768x384.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" width=\"800\" height=\"300\"   \/><\/a><\/div>","protected":false},"excerpt":{"rendered":"<p>LATINA &#8211; Qui trovate Prima Pagina, in un file audio di pochi minuti, i titoli di Latina Editoriale Oggi e del Messaggero Latina.<\/p>\n","protected":false},"author":60,"featured_media":387143,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[2358],"tags":[4448,5022,23,1069,2154,3252,5357,4450,4449,5356],"class_list":["post-387136","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-titoli","tag-giornali-di-latina","tag-il-messaggero-latina","tag-latina","tag-latina-oggi","tag-notizie-di-latina","tag-prima-pagina","tag-prima-pagina-latina","tag-prime-pagine-latina","tag-quotidiani-latina","tag-rassegna-stampa-latina"],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/387136","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/users\/60"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/comments?post=387136"}],"version-history":[{"count":1,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/387136\/revisions"}],"predecessor-version":[{"id":387144,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/387136\/revisions\/387144"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/media\/387143"}],"wp:attachment":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/media?parent=387136"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/categories?post=387136"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/tags?post=387136"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}