{"id":387510,"date":"2025-10-07T08:37:35","date_gmt":"2025-10-07T06:37:35","guid":{"rendered":"https:\/\/www.radioluna.it\/news\/?p=387510"},"modified":"2025-10-07T08:37:35","modified_gmt":"2025-10-07T06:37:35","slug":"latina-genitori-di-alunni-con-disabilita-scrivono-al-comune","status":"publish","type":"post","link":"https:\/\/www.radioluna.it\/news\/2025\/10\/latina-genitori-di-alunni-con-disabilita-scrivono-al-comune\/","title":{"rendered":"Latina, genitori di alunni con disabilit\u00e0 scrivono al Comune"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p style=\"text-align: justify;\" data-start=\"347\" data-end=\"654\">Profonda preoccupazione tra le famiglie di studenti con disabilit\u00e0 e bisogni educativi speciali di Latina per la mancata attivazione, a settimane dall\u2019inizio dell\u2019anno scolastico, del servizio di assistenza specialistica e di comunicazione aumentativa e alternativa negli istituti del territorio comunale.<\/p>\n<p style=\"text-align: justify;\" data-start=\"347\" data-end=\"654\">In una lettera inviata all\u2019amministrazione, un gruppo di genitori \u2013 con il sostegno dell\u2019associazione LatinAutismo APS \u2013 denuncia la situazione definendola \u201cinaccettabile e discriminatoria\u201d. A oggi, spiegano, i loro figli continuano a frequentare la scuola senza il supporto di figure professionali fondamentali per garantire inclusione e diritto allo studio, con conseguenze pesanti per studenti, famiglie e personale docente.<\/p>\n<p style=\"text-align: justify;\" data-start=\"1087\" data-end=\"1414\">\u201cAlcuni insegnanti, non potendo garantire la presenza costante con l\u2019alunno, chiedono ai genitori di anticipare l\u2019uscita dei bambini\u201d, si legge nella nota. \u201cIn altri casi, i minori restano a scuola senza il necessario supporto, costringendo le famiglie a vivere le giornate lavorative in uno stato di ansia e preoccupazione\u201d.<\/p>\n<p style=\"text-align: justify;\" data-start=\"1416\" data-end=\"1933\">I genitori ricordano inoltre come gi\u00e0 durante le colonie estive la mancanza di assistenza avesse escluso molti bambini con disabilit\u00e0 da esperienze di socializzazione e crescita. Preoccupa anche l\u2019ipotesi, trapelata nelle ultime settimane, di una possibile fusione tra le figure dell\u2019assistente specialistico e quella dell\u2019assistente alla comunicazione aumentativa e alternativa, che \u2013 si sottolinea \u2013 \u201crischierebbe di compromettere la qualit\u00e0 e la specificit\u00e0 del sostegno agli alunni con disabilit\u00e0 comunicative\u201d.<\/p>\n<p style=\"text-align: justify;\" data-start=\"1935\" data-end=\"2236\">La lettera richiama infine i principi sanciti dalla Costituzione, dalla Convenzione ONU sui diritti delle persone con disabilit\u00e0 e dalla legge 104\/1992, ribadendo come l\u2019attuale situazione nel territorio di Latina \u201cconfiguri una discriminazione diretta e indiretta\u201d ai sensi della normativa vigente.<\/p>\n<p style=\"text-align: justify;\" data-start=\"2238\" data-end=\"2477\">Le famiglie chiedono quindi al Comune un intervento immediato per garantire l\u2019attivazione dei servizi e la tutela del diritto all\u2019istruzione dei propri figli, confidando in una risposta formale e tempestiva da parte dell\u2019amministrazione.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Profonda preoccupazione tra le famiglie di studenti con disabilit\u00e0 e bisogni educativi speciali di Latina per la mancata attivazione, a settimane dall\u2019inizio dell\u2019anno scolastico, del servizio di assistenza specialistica e di comunicazione aumentativa e alternativa negli istituti del territorio comunale. In una lettera inviata all\u2019amministrazione, un gruppo di genitori \u2013 con il sostegno dell\u2019associazione LatinAutismo [&hellip;]<\/p>\n","protected":false},"author":5443,"featured_media":387511,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[735,7],"tags":[],"class_list":["post-387510","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-attualita","category-cronaca"],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/387510","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/users\/5443"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/comments?post=387510"}],"version-history":[{"count":1,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/387510\/revisions"}],"predecessor-version":[{"id":387512,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/387510\/revisions\/387512"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/media\/387511"}],"wp:attachment":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/media?parent=387510"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/categories?post=387510"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/tags?post=387510"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}