{"id":387793,"date":"2025-10-10T12:14:58","date_gmt":"2025-10-10T10:14:58","guid":{"rendered":"https:\/\/www.radioluna.it\/news\/?p=387793"},"modified":"2025-10-10T12:19:09","modified_gmt":"2025-10-10T10:19:09","slug":"inaugurato-in-piazza-del-popolo-il-villaggio-della-protezione-civile","status":"publish","type":"post","link":"https:\/\/www.radioluna.it\/news\/2025\/10\/inaugurato-in-piazza-del-popolo-il-villaggio-della-protezione-civile\/","title":{"rendered":"Inaugurato in piazza del Popolo il Villaggio della Protezione Civile"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p style=\"text-align: justify;\"><strong>LATINA &#8211;<\/strong> E\u2019 stato inaugurato questa mattina il Villaggio della Protezione Civile in piazza del Popolo a Latina che \u00e8 ora aperto al pubblico. I primi visitatori sono stati ragazzi delle scuole che hanno potuto vedere la vicino una Sala operativa mobile, mezzi e dotazioni usate da professionisti e volontari del sistema regionale del Lazio. A loro sono state date informazioni utili nella vita di tutti i giorni e quelle necessarie ad affrontare eventuali emergenze, come ha raccontano al microfono di Antonella Melito la vice commissaria della Uoc di Protezione civile Angelina Carnevale.<\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-387793-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2025\/10\/angelina-carnevale-prot-civmp3.mp3?_=1\" \/><a href=\"https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2025\/10\/angelina-carnevale-prot-civmp3.mp3\">https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2025\/10\/angelina-carnevale-prot-civmp3.mp3<\/a><\/audio>\n<p style=\"text-align: justify;\">\u00a0Al taglio del nastro dell&#8217;evento clou della Settimana della Protezione Civile, padrona di casa la sindaca di Latina Matilde Celentano, presenti la dottoressa Monica Perna Vicaria del Prefetto, l&#8217;assessore regionale Pasquale Ciacciarelli e l&#8217;assessore comunale Gianluca di Cocco.<\/p>\n<p>&nbsp;<\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-387793-2\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2025\/10\/ciacciarelli.mp3?_=2\" \/><a href=\"https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2025\/10\/ciacciarelli.mp3\">https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2025\/10\/ciacciarelli.mp3<\/a><\/audio>\n<audio class=\"wp-audio-shortcode\" id=\"audio-387793-3\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2025\/10\/protezione-civile-Di-Cocco.mp3?_=3\" \/><a href=\"https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2025\/10\/protezione-civile-Di-Cocco.mp3\">https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2025\/10\/protezione-civile-Di-Cocco.mp3<\/a><\/audio>\n<p>Carlo Costantini, responsabile dell&#8217;Emergenza e della Sala operativa regionale del Lazio ha ringraziato la grande rete dei volontari<\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-387793-4\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2025\/10\/carlo-costantini-protezione-civile.mp3?_=4\" \/><a href=\"https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2025\/10\/carlo-costantini-protezione-civile.mp3\">https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2025\/10\/carlo-costantini-protezione-civile.mp3<\/a><\/audio>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>LATINA &#8211; E\u2019 stato inaugurato questa mattina il Villaggio della Protezione Civile in piazza del Popolo a Latina che \u00e8 ora aperto al pubblico. I primi visitatori sono stati ragazzi delle scuole che hanno potuto vedere la vicino una Sala operativa mobile, mezzi e dotazioni usate da professionisti e volontari del sistema regionale del Lazio. [&hellip;]<\/p>\n","protected":false},"author":62,"featured_media":387794,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"gallery","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[735,2310,7],"tags":[],"class_list":["post-387793","post","type-post","status-publish","format-gallery","has-post-thumbnail","hentry","category-attualita","category-audio","category-cronaca","post_format-post-format-gallery"],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/387793","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/users\/62"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/comments?post=387793"}],"version-history":[{"count":2,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/387793\/revisions"}],"predecessor-version":[{"id":387808,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/387793\/revisions\/387808"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/media\/387794"}],"wp:attachment":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/media?parent=387793"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/categories?post=387793"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/tags?post=387793"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}