{"id":387826,"date":"2025-10-10T17:00:29","date_gmt":"2025-10-10T15:00:29","guid":{"rendered":"https:\/\/www.radioluna.it\/news\/?p=387826"},"modified":"2025-10-10T17:05:55","modified_gmt":"2025-10-10T15:05:55","slug":"terracina-viola-il-divieto-di-avvicinamento-e-danneggia-lauto-dellex","status":"publish","type":"post","link":"https:\/\/www.radioluna.it\/news\/2025\/10\/terracina-viola-il-divieto-di-avvicinamento-e-danneggia-lauto-dellex\/","title":{"rendered":"Terracina, viola il divieto di avvicinamento e danneggia l\u2019auto dell\u2019ex"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p style=\"text-align: justify;\" data-start=\"303\" data-end=\"724\">\u00c8 stato arrestato dai Carabinieri della Stazione di Terracina un uomo di 32 anni, gi\u00e0 noto alle forze dell\u2019ordine e sottoposto alla misura cautelare del divieto di avvicinamento all\u2019ex coniuge con l\u2019applicazione del braccialetto elettronico. L\u2019arresto \u00e8 scattato in flagranza differita per violazione del divieto imposto dall\u2019Autorit\u00e0 giudiziaria e danneggiamento in un contesto di stalking.<\/p>\n<p style=\"text-align: justify;\" data-start=\"726\" data-end=\"1043\">L\u2019intervento dei militari \u00e8 partito dopo la querela presentata da una donna di 32 anni, che aveva denunciato un nuovo avvicinamento dell\u2019ex compagno, nonostante il divieto. Al momento del sopralluogo l\u2019uomo non era pi\u00f9 sul posto, ma le indagini avviate dai Carabinieri hanno permesso di ricostruire quanto accaduto.<\/p>\n<p style=\"text-align: justify;\" data-start=\"1045\" data-end=\"1481\">Grazie all\u2019analisi delle immagini dei sistemi di videosorveglianza e soprattutto alla verifica dei tracciati del braccialetto elettronico, eseguita dalla Centrale Operativa della Compagnia di Latina, i militari hanno accertato che il trentaduenne si era recato nel parcheggio dell\u2019ospedale di Terracina, dove si trovava la donna per motivi di studio, violando il limite di 500 metri imposto dalla misura cautelare.<\/p>\n<p style=\"text-align: justify;\" data-start=\"1483\" data-end=\"1671\">Dalle verifiche \u00e8 emerso inoltre che l\u2019uomo aveva forato i quattro pneumatici dell\u2019auto dell\u2019ex compagna, danneggiando anche uno specchietto retrovisore e il tappo del serbatoio.<\/p>\n<p style=\"text-align: justify;\" data-start=\"1673\" data-end=\"1822\">Terminate le formalit\u00e0 di rito, il trentaduenne \u00e8 stato trasferito alla Casa Circondariale di Latina, a disposizione dell\u2019Autorit\u00e0 Giudiziaria.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c8 stato arrestato dai Carabinieri della Stazione di Terracina un uomo di 32 anni, gi\u00e0 noto alle forze dell\u2019ordine e sottoposto alla misura cautelare del divieto di avvicinamento all\u2019ex coniuge con l\u2019applicazione del braccialetto elettronico. L\u2019arresto \u00e8 scattato in flagranza differita per violazione del divieto imposto dall\u2019Autorit\u00e0 giudiziaria e danneggiamento in un contesto di stalking. [&hellip;]<\/p>\n","protected":false},"author":5443,"featured_media":387827,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[7,2428],"tags":[],"class_list":["post-387826","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cronaca","category-primo-piano"],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/387826","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/users\/5443"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/comments?post=387826"}],"version-history":[{"count":2,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/387826\/revisions"}],"predecessor-version":[{"id":387829,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/387826\/revisions\/387829"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/media\/387827"}],"wp:attachment":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/media?parent=387826"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/categories?post=387826"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/tags?post=387826"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}