{"id":388175,"date":"2025-10-15T10:05:59","date_gmt":"2025-10-15T08:05:59","guid":{"rendered":"https:\/\/www.radioluna.it\/news\/?p=388175"},"modified":"2025-10-17T10:51:35","modified_gmt":"2025-10-17T08:51:35","slug":"controlli-dellanas-al-cavalcavia-di-borgo-piave-traffico-in-tilt-sulla-pontina-e-in-citta","status":"publish","type":"post","link":"https:\/\/www.radioluna.it\/news\/2025\/10\/controlli-dellanas-al-cavalcavia-di-borgo-piave-traffico-in-tilt-sulla-pontina-e-in-citta\/","title":{"rendered":"Lavori non programmati al piano viabile della Pontina a Borgo Piave, traffico in tilt anche in citt\u00e0"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p><strong>LATINA &#8211; <\/strong>Traffico in tilt questa mattina sulla Pontina e in citt\u00e0 a causa della chiusura del tratto in corrispondenza di Borgo Piave dove l&#8217;Anas ha svolto lavori urgenti non programmati di ripristino del piano viabile in corrispondenza di un pericoloso avvallamento che si trova all&#8217;altezza del cavalcavia.<\/p>\n<p>La SS 148 \u00e8 stata chiusa all&#8217;altezza del km 67,00 in entrambe i sensi di marcia con forti ripercussioni sul traffico soprattutto in direzione della Capitale dove le auto sono obbligate a confluire sulla gi\u00e0 insufficiente rotatoria della frazione. Si sono formati chilometri di coda.<\/p>\n<p>Secondo quanto riferito da Anas i lavori non erano rinviabili e le squadre lavoreranno fino alle 15 circa, solo allora il cantiere dovrebbe essere rimosso.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>LATINA &#8211; Traffico in tilt questa mattina sulla Pontina e in citt\u00e0 a causa della chiusura del tratto in corrispondenza di Borgo Piave dove l&#8217;Anas ha svolto lavori urgenti non programmati di ripristino del piano viabile in corrispondenza di un pericoloso avvallamento che si trova all&#8217;altezza del cavalcavia. La SS 148 \u00e8 stata chiusa all&#8217;altezza [&hellip;]<\/p>\n","protected":false},"author":62,"featured_media":213584,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[7],"tags":[],"class_list":["post-388175","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cronaca"],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/388175","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/users\/62"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/comments?post=388175"}],"version-history":[{"count":3,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/388175\/revisions"}],"predecessor-version":[{"id":388188,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/388175\/revisions\/388188"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/media\/213584"}],"wp:attachment":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/media?parent=388175"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/categories?post=388175"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/tags?post=388175"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}