{"id":392757,"date":"2025-12-20T17:43:51","date_gmt":"2025-12-20T16:43:51","guid":{"rendered":"https:\/\/www.radioluna.it\/news\/?p=392757"},"modified":"2025-12-20T17:43:51","modified_gmt":"2025-12-20T16:43:51","slug":"sermonta-realizzato-il-nuovo-campetto-polivalente","status":"publish","type":"post","link":"https:\/\/www.radioluna.it\/news\/2025\/12\/sermonta-realizzato-il-nuovo-campetto-polivalente\/","title":{"rendered":"Sermonta, realizzato il nuovo campetto polivalente"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p style=\"text-align: justify;\" data-start=\"73\" data-end=\"535\">Un nuovo campo sportivo polivalente \u00e8 stato realizzato a Sermoneta e messo a disposizione della comunit\u00e0. Si sono conclusi infatti i lavori finanziati attraverso il bando regionale \u201cSport e Salute\u201d, ottenuti dall\u2019amministrazione comunale guidata dal sindaco Giuseppina Giovannoli, che hanno consentito la riqualificazione di un\u2019area laterale al campo sportivo principale del centro comunale \u201cLamberto Milani\u201d, destinata alla pratica del tennis e della pallavolo.<\/p>\n<p style=\"text-align: justify;\" data-start=\"537\" data-end=\"931\">L\u2019intervento ha previsto la posa di un nuovo tappetino sintetico, l\u2019installazione dell\u2019illuminazione a led e il completo ripristino della rete perimetrale, rendendo l\u2019impianto pi\u00f9 moderno, funzionale e fruibile anche nelle ore serali. Un ulteriore spazio sportivo che va ad arricchire l\u2019offerta gi\u00e0 presente sul territorio comunale, a beneficio delle societ\u00e0 sportive e delle nuove generazioni.<\/p>\n<p style=\"text-align: justify;\" data-start=\"933\" data-end=\"1549\">\u00abSi tratta di un nuovo spazio messo a disposizione delle associazioni che operano a Sermoneta, per offrire sempre pi\u00f9 opportunit\u00e0 di praticare diverse discipline sportive \u2013 spiega l\u2019assessore ai lavori pubblici Nicola Minniti \u2013. Come amministrazione continuiamo a investire sugli impianti sportivi comunali: un anno fa abbiamo restituito alla comunit\u00e0 la pista di atletica, con interventi di riqualificazione energetica e la ristrutturazione degli spogliatoi finanziati con fondi di bilancio, intitolando l\u2019intero complesso alla memoria del maratoneta sermonetano Lamberto Milani, quattro volte recordman del mondo\u00bb.<\/p>\n<p style=\"text-align: justify;\" data-start=\"1551\" data-end=\"2001\">Nel quadro degli interventi realizzati, l\u2019amministrazione ha inoltre dotato il parco di Monticchio di una seconda palestra all\u2019aperto, dopo quella di Pontenuovo, installato canestri per il basket e riqualificato diversi campetti presenti sul territorio, tra Sermoneta Scalo, Campo Vecchio nel centro storico e Monticchio. Sono gi\u00e0 in corso valutazioni per la partecipazione a nuovi bandi finalizzati all\u2019implementazione dei servizi sportivi comunali.<\/p>\n<p style=\"text-align: justify;\" data-start=\"2003\" data-end=\"2537\">\u00abStiamo lavorando per trasformare il centro comunale Lamberto Milani in una vera e propria cittadella dello sport \u2013 aggiunge il delegato allo sport Mauro Lorenzo Mariotti \u2013 ampliando l\u2019offerta per giovani e adulti e garantendo alle associazioni sportive locali strutture adeguate e funzionali. A Sermoneta \u00e8 possibile praticare numerose discipline, dal volley al basket, entrambi quest\u2019anno in serie C, fino a pattinaggio, tennis, atletica leggera, ciclismo, arti marziali e podistica, promuovendo salute, inclusione e sano agonismo\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un nuovo campo sportivo polivalente \u00e8 stato realizzato a Sermoneta e messo a disposizione della comunit\u00e0. Si sono conclusi infatti i lavori finanziati attraverso il bando regionale \u201cSport e Salute\u201d, ottenuti dall\u2019amministrazione comunale guidata dal sindaco Giuseppina Giovannoli, che hanno consentito la riqualificazione di un\u2019area laterale al campo sportivo principale del centro comunale \u201cLamberto Milani\u201d, [&hellip;]<\/p>\n","protected":false},"author":5443,"featured_media":392758,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[735,7],"tags":[],"class_list":["post-392757","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-attualita","category-cronaca"],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/392757","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/users\/5443"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/comments?post=392757"}],"version-history":[{"count":1,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/392757\/revisions"}],"predecessor-version":[{"id":392759,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/392757\/revisions\/392759"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/media\/392758"}],"wp:attachment":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/media?parent=392757"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/categories?post=392757"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/tags?post=392757"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}