{"id":424803,"date":"2026-03-19T11:59:48","date_gmt":"2026-03-19T10:59:48","guid":{"rendered":"https:\/\/www.radioluna.it\/news\/?p=424803"},"modified":"2026-03-19T11:59:48","modified_gmt":"2026-03-19T10:59:48","slug":"sabato-21-marzo-al-teatro-santa-maria-goretti-di-latina-tre-preti-per-una-besciamella","status":"publish","type":"post","link":"https:\/\/www.radioluna.it\/news\/2026\/03\/sabato-21-marzo-al-teatro-santa-maria-goretti-di-latina-tre-preti-per-una-besciamella\/","title":{"rendered":"Sabato 21 marzo al Teatro Santa Maria Goretti di Latina\u00a0 &#8220;Tre preti per una besciamella&#8221;"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p>Sabato 21 marzo alle 20.30 al\u00a0 Teatro Santa Maria Goretti\u00a0 di Latina torna la rassegna de \u201cIl Teatro in Citt\u00e0\u201d, il Festival dedicato al teatro amatoriale creato da APS Cantiere dell\u2019Arte in collaborazione con l\u2019associazione culturale teatrale I SognAttori.<\/p>\n<p>Sul palco del teatro sito in Viale XVIII Dicembre 21 riflettori accesi sulla Compagnia dei Teatranti APS con lo spettacolo &#8220;Tre preti per una besciamella&#8221; firmata da Tonio Logoluso.<\/p>\n<p>Logoluso, attore, regista e scrittore \u00e8 anche il fondatore e direttore artistico della Compagnia &#8220;Teatro delle Onde&#8221; di Bisceglie nonch\u00e9 direttore artistico del Teatro Don Luigi Sturzo della stessa citt\u00e0, in qualit\u00e0 di autore ha vinto il premio nazionale per testi teatrali &#8220;Giorgia Vignoli&#8221; con il testo \u201cChrissy delle siepi\u201d, selezionato anche dal Centro Italiano Ricerche Teatrali di Milano.<\/p>\n<p>In scena diretti da Vincenzo Matichecchia ci saranno: Enzo Ciani, Enzo Matichecchia, Giuseppe Sasso, Cosimo Boccassini, Lella Mastrapasqua, Noemi Mazzola, Elisabetta Tortora, Mauro Di Cugno. Tecnico: Mariangela Di Liddo.<\/p>\n<p>La direzione artistica della rassegna \u201cIl Teatro in Citt\u00e0\u201d \u00e8 affidata a Giovanni Iovine, con direzione esecutiva di Massimo Ciufo e comunicazione social curata da Ilenia Scaccia. Il festival proseguir\u00e0 fino al 9 maggio 2026, data della serata conclusiva con la proclamazione della compagnia vincitrice.<\/p>\n<p>I prossimi appuntamenti della manifestazione saranno con Gli Amici del Teatro di Pianiga che si esibiranno sabato 11 aprile con <em>I 39 scalini, mentre <\/em>la Compagnia Teatrale Costellazione presenter\u00e0 sabato 18 aprile <em>La cattedrale<\/em>. La serata finale si terr\u00e0 sabato 9 maggio con la proclamazione della compagnia vincitrice.<\/p>\n<p>La giuria che assegner\u00e0 il premio alla migliore compagnia \u00e8 composta da: Giovanni Musella, Massimiliano De Majo, Roberta Colazingari, Dina Tomezzoli e Roberta Sciarretta.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sabato 21 marzo alle 20.30 al\u00a0 Teatro Santa Maria Goretti\u00a0 di Latina torna la rassegna de \u201cIl Teatro in Citt\u00e0\u201d, il Festival dedicato al teatro amatoriale creato da APS Cantiere dell\u2019Arte in collaborazione con l\u2019associazione culturale teatrale I SognAttori. Sul palco del teatro sito in Viale XVIII Dicembre 21 riflettori accesi sulla Compagnia dei Teatranti [&hellip;]<\/p>\n","protected":false},"author":5444,"featured_media":424804,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16,734],"tags":[],"class_list":["post-424803","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-appuntamenti","category-evidenza"],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/424803","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/users\/5444"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/comments?post=424803"}],"version-history":[{"count":1,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/424803\/revisions"}],"predecessor-version":[{"id":424805,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/424803\/revisions\/424805"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/media\/424804"}],"wp:attachment":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/media?parent=424803"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/categories?post=424803"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/tags?post=424803"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}