{"id":426551,"date":"2026-04-13T09:09:58","date_gmt":"2026-04-13T07:09:58","guid":{"rendered":"https:\/\/www.radioluna.it\/news\/?p=426551"},"modified":"2026-04-13T09:09:58","modified_gmt":"2026-04-13T07:09:58","slug":"arti-marziali-su-radio-immagine-lintervista-al-maestro-mario-cristofaro-e-al-suo-allievo-yuri-quaranta","status":"publish","type":"post","link":"https:\/\/www.radioluna.it\/news\/2026\/04\/arti-marziali-su-radio-immagine-lintervista-al-maestro-mario-cristofaro-e-al-suo-allievo-yuri-quaranta\/","title":{"rendered":"Arti Marziali, su Radio Immagine l&#8217;intervista al maestro Mario Cristofaro e al suo allievo Yuri Quaranta"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p style=\"text-align: justify;\">LATINA &#8211; Lunedi 13 aprile alle ore 15:30, in diretta su Radio Immagine, andr\u00e0 in onda un\u2019intervista con due protagonisti assoluti delle arti marziali della provincia di Latina: il maestro Mario Cristofaro e il suo allievo Yuri Quaranta.<br \/>\nI due atleti, primi campioni del mondo nel loro ambito a rappresentare il territorio pontino, racconteranno ai microfoni radiofonici il percorso che li ha portati a raggiungere traguardi cos\u00ec prestigiosi, soffermandosi in particolare sulla recente nomina a delegati provinciali per lo sport dell\u2019UNICEF. Un incarico di grande responsabilit\u00e0 che unisce sport e impegno sociale, con l\u2019obiettivo di promuovere valori educativi e solidali tra i giovani.<br \/>\nDurante l\u2019intervista, Cristofaro e Quaranta parleranno anche di uno degli eventi pi\u00f9 attesi dell\u2019anno: la \u201cPartita del Cuore\u201d, un evento nazionale che vedr\u00e0 coinvolta la nazionale attori e quella dei vigili del fuoco e che si terr\u00e0 il 5 giugno presso lo Stadio Domenico Francioni di Latina.<br \/>\nL\u2019evento, che si svolger\u00e0 davanti a circa 9.000 spettatori, li vedr\u00e0 protagonisti anche fuori dal tatami: saliranno infatti sul palco come ospiti d\u2019onore, testimoniando il legame tra sport, spettacolo e solidariet\u00e0.<br \/>\nI due campioni illustreranno anche i prossimi impegni sportivi, tra seminari, competizioni e nuovi obiettivi da raggiungere. Un percorso in continua evoluzione, fatto di disciplina, sacrificio e passione, che continua a portare in alto il nome della provincia di Latina nel panorama internazionale delle arti marziali. Un appuntamento imperdibile per gli appassionati di sport e per chi crede nei valori positivi che lo sport pu\u00f2 trasmettere.<\/p>\n<div id=\"radio-650341371\" class=\"radio-dopo-il-contenuto radio-entity-placement\"><a href=\"https:\/\/concessionari-suzuki.it\/bodema\/\" aria-label=\"Bodema 1200&#215;600 banner Suzuki_AX\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2025\/05\/Bodema-1200x600-banner-Suzuki_AX.jpg\" alt=\"\"  srcset=\"https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2025\/05\/Bodema-1200x600-banner-Suzuki_AX.jpg 1200w, https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2025\/05\/Bodema-1200x600-banner-Suzuki_AX-768x384.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" width=\"800\" height=\"300\"   \/><\/a><\/div>","protected":false},"excerpt":{"rendered":"<p>LATINA &#8211; Lunedi 13 aprile alle ore 15:30, in diretta su Radio Immagine, andr\u00e0 in onda un\u2019intervista con due protagonisti assoluti delle arti marziali della provincia di Latina: il maestro Mario Cristofaro e il suo allievo Yuri Quaranta. I due atleti, primi campioni del mondo nel loro ambito a rappresentare il territorio pontino, racconteranno ai [&hellip;]<\/p>\n","protected":false},"author":5430,"featured_media":426552,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-426551","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport"],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/426551","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/users\/5430"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/comments?post=426551"}],"version-history":[{"count":1,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/426551\/revisions"}],"predecessor-version":[{"id":426553,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/426551\/revisions\/426553"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/media\/426552"}],"wp:attachment":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/media?parent=426551"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/categories?post=426551"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/tags?post=426551"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}