{"id":430109,"date":"2026-05-31T10:40:46","date_gmt":"2026-05-31T08:40:46","guid":{"rendered":"https:\/\/www.radioluna.it\/news\/?p=430109"},"modified":"2026-05-31T10:40:46","modified_gmt":"2026-05-31T08:40:46","slug":"santo-stefano-lex-carcere-e-salvo-il-commissario-marinello-completata-la-messa-in-sicurezza-ora-serve-lapprodo","status":"publish","type":"post","link":"https:\/\/www.radioluna.it\/news\/2026\/05\/santo-stefano-lex-carcere-e-salvo-il-commissario-marinello-completata-la-messa-in-sicurezza-ora-serve-lapprodo\/","title":{"rendered":"Santo Stefano, l&#8217;ex carcere \u00e8 salvo. Il commissario Marinello: &#8220;Completata la messa in sicurezza, ora serve l&#8217;approdo&#8221;"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 33%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-430109 gallery-columns-3 gallery-size-thumbnail'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.radioluna.it\/news\/2026\/05\/santo-stefano-lex-carcere-e-salvo-il-commissario-marinello-completata-la-messa-in-sicurezza-ora-serve-lapprodo\/whatsapp-image-2026-05-31-at-09-15-01\/'><img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"96\" src=\"https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-31-at-09.15.01.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-430113\" srcset=\"https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-31-at-09.15.01.jpeg 1920w, https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-31-at-09.15.01-768x576.jpeg 768w, https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-31-at-09.15.01-1536x1152.jpeg 1536w\" sizes=\"auto, (max-width: 128px) 100vw, 128px\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-430113'>\n\t\t\t\tL&#8217;ATTUALE APPRODO SULL&#8217;ISOLOTTO\n\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.radioluna.it\/news\/2026\/05\/santo-stefano-lex-carcere-e-salvo-il-commissario-marinello-completata-la-messa-in-sicurezza-ora-serve-lapprodo\/whatsapp-image-2026-05-31-at-09-16-11\/'><img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"96\" src=\"https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-31-at-09.16.11.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-430111\" srcset=\"https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-31-at-09.16.11.jpeg 1920w, https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-31-at-09.16.11-768x576.jpeg 768w, https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-31-at-09.16.11-1536x1152.jpeg 1536w\" sizes=\"auto, (max-width: 128px) 100vw, 128px\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-430111'>\n\t\t\t\tLA PRIMA NOSTRA ALLESTITA A SANTO STEFANO \n\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.radioluna.it\/news\/2026\/05\/santo-stefano-lex-carcere-e-salvo-il-commissario-marinello-completata-la-messa-in-sicurezza-ora-serve-lapprodo\/whatsapp-image-2026-05-31-at-09-16-10\/'><img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"96\" src=\"https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-31-at-09.16.10.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-430112\" srcset=\"https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-31-at-09.16.10.jpeg 1920w, https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-31-at-09.16.10-768x576.jpeg 768w, https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-31-at-09.16.10-1536x1152.jpeg 1536w\" sizes=\"auto, (max-width: 128px) 100vw, 128px\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-430112'>\n\t\t\t\tCOMPLETATA LA MESSA IN SICUREZZA DELL&#8217;EX CARCERE DI SANTO STEFANO \n\t\t\t\t<\/dd><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n\n<p style=\"text-align: justify;\"><strong>VENTOTENE &#8211;\u00a0<\/strong> Si \u00e8 conclusa la messa in sicurezza dell&#8217;ex carcere borbonico di Santo Stefano, passaggio complesso e preliminare ai lavori di restauro e valorizzazione del bene per trasformarlo in un polo museale, di memoria storica e ricerca e di alta formazione europea. Nei giorni scorsi il neo commissario di Governo Giuseppe Marinello, \u00e8 approdato sull&#8217;isolotto per verificare di persona lo stato dei lavori, spiegando che il prossimo step sar\u00e0 ottenere l&#8217;autorizzazione per un approdo sicuro, visto che ad oggi (v.foto) arrivare sull&#8217;isola \u00e8 complesso e possibile solo con ottime condizioni meteomarine. Ma il primo approdo era stato bocciato perch\u00e9 ritenuto fonte di danni per la posidonia, la pianta marina che d\u00e0 ossigeno al mare.<\/p>\n<p style=\"text-align: justify;\">\u00abQueste sono quattro settimane decisive &#8211; ha detto ai giornalisti presenti Marinello\u00a0 &#8211; Attendiamo che la Commissione VIA-VAS del Ministero dell&#8217;Ambiente rivaluti le richieste. Se tutto dovesse andare come noi auspichiamo &#8211; spiega Giuseppe Marinello &#8211; , grazie agli studi che la gestione commissariale ha commissionato ad autorit\u00e0 scientifiche di assoluto prestigio e di assoluta valenza, riusciremo a entrare in un momento nuovo per Santo Stefano, cio\u00e8 nella possibilit\u00e0 di realizzare un approdo che garantisca l&#8217;accessibilit\u00e0 all&#8217;isola quanto pi\u00f9 estesa possibile, tendendo all&#8217;accessibilit\u00e0 universale\u00bb. Gli studi di cui parla Marinello, avrebbero escluso la presenza di posidonia nell&#8217;area in cui sarebbe realizzato l&#8217;approdo.<\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-430109-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2026\/05\/commissario-ventotene-approdo.mp3?_=1\" \/><a href=\"https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2026\/05\/commissario-ventotene-approdo.mp3\">https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2026\/05\/commissario-ventotene-approdo.mp3<\/a><\/audio>\n<p style=\"text-align: justify;\">Intanto sull&#8217;isolotto, dove riprenderanno a breve le visite guidate, \u00e8 stata allestita la mostra &#8220;le sfide di Santo Stefano&#8221; curata da Sabina Minutillo Turtur che ripercorre la storia del luogo e dell&#8217;ex ergastolo.<\/p>\n<div id=\"radio-2760888431\" class=\"radio-dopo-il-contenuto radio-entity-placement\"><a href=\"https:\/\/concessionari-suzuki.it\/bodema\/\" aria-label=\"Bodema 1200&#215;600 banner Suzuki_AX\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2025\/05\/Bodema-1200x600-banner-Suzuki_AX.jpg\" alt=\"\"  srcset=\"https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2025\/05\/Bodema-1200x600-banner-Suzuki_AX.jpg 1200w, https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2025\/05\/Bodema-1200x600-banner-Suzuki_AX-768x384.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" width=\"800\" height=\"300\"   \/><\/a><\/div>","protected":false},"excerpt":{"rendered":"<p>VENTOTENE &#8211;\u00a0 Si \u00e8 conclusa la messa in sicurezza dell&#8217;ex carcere borbonico di Santo Stefano, passaggio complesso e preliminare ai lavori di restauro e valorizzazione del bene per trasformarlo in un polo museale, di memoria storica e ricerca e di alta formazione europea. Nei giorni scorsi il neo commissario di Governo Giuseppe Marinello, \u00e8 approdato [&hellip;]<\/p>\n","protected":false},"author":62,"featured_media":430112,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[735,15],"tags":[],"class_list":["post-430109","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-attualita","category-cultura"],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/430109","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/users\/62"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/comments?post=430109"}],"version-history":[{"count":4,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/430109\/revisions"}],"predecessor-version":[{"id":430134,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/430109\/revisions\/430134"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/media\/430112"}],"wp:attachment":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/media?parent=430109"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/categories?post=430109"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/tags?post=430109"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}