{"id":430126,"date":"2026-05-31T10:09:40","date_gmt":"2026-05-31T08:09:40","guid":{"rendered":"https:\/\/www.radioluna.it\/news\/?p=430126"},"modified":"2026-05-31T10:42:29","modified_gmt":"2026-05-31T08:42:29","slug":"formia-torna-a-casa-il-bambinello-ligneo-di-maranola-rubato-nel-2015","status":"publish","type":"post","link":"https:\/\/www.radioluna.it\/news\/2026\/05\/formia-torna-a-casa-il-bambinello-ligneo-di-maranola-rubato-nel-2015\/","title":{"rendered":"Formia, torna a casa il Bambinello ligneo di Maranola rubato nel 2015"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p style=\"text-align: justify;\"><strong>FORMIA<\/strong> &#8211; A undici anni dalla sua sparizione a seguito di un furto, \u00e8 tornato nel pomeriggio di ieri alla comunit\u00e0 di Maranola il Bambinello di Sant&#8217;Antonio, uno dei simboli religiosi e culturali pi\u00f9 amati. La scultura lignea policroma risalente alla fine del XVIII secolo era stata rubata a maggio del 2015.<\/p>\n<p style=\"text-align: justify;\">Sono stati i carabinieri a svolgere le indagini, e in particolare i militari della Stazione di Genzano di Lucania che monitorando le piattaforme virtuali di interscambio commerciale, hanno intercettato una transazione sospetta, &#8220;che lasciava presagire\u00a0 &#8211; si legge in una nota dell&#8217;Arma &#8211; l&#8217;imminente e definitivo occultamento del bene, ha imposto una fulminea accelerazione operativa&#8221;.<\/p>\n<p style=\"text-align: justify;\">In un&#8217;abitazione privata del comune lucano, la perquisizione eseguita dai militari ha permesso di recuperare l&#8217;opera d&#8217;arte il manufatto che \u00e8 stata trovata integra, ma gi\u00e0 confezionata e imballata, pronta per essere consegnata a un un corriere destinata all&#8217;estero a un ignoto acquirente che aveva gi\u00e0 pagato il prezzo. &#8220;Se l&#8217;opera avesse varcato i confini nazionali, incanalandosi nei circuiti sommersi del collezionismo internazionale privato, sarebbe andata perduta per sempre&#8221;, sottolinea l&#8217;Arma.<\/p>\n<p style=\"text-align: justify;\">La conferma definitiva dell&#8217;origine del bene \u00e8 stata ottenuta attraverso l&#8217;interrogazione della Banca Dati del Comando Carabinieri Tutela Patrimonio Culturale, il pi\u00f9 grande database al mondo dedicato ai beni culturali illecitamente sottratti. L&#8217;incrocio dei dati ha permesso di accertare l&#8217;esatta corrispondenza tra la statua rinvenuta in provincia di Potenza e quella inserita nei sistemi undici anni prima, a seguito del furto perpetrato nella notte tra il 7 e l&#8217;8 maggio 2015 all&#8217;interno della Chiesa della Santissima Annunziata di Maranola.<\/p>\n<p style=\"text-align: justify;\">Ottenuto il necessario nulla osta al dissequestro da parte delle competenti Autorit\u00e0 Giudiziarie, il rientro dell\u2019opera \u00e8 stato pianificato d&#8217;intesa con le Autorit\u00e0 Ecclesiastiche.<\/p>\n<p style=\"text-align: justify;\">L&#8217;evento ha vissuto i suoi momenti pi\u00f9 toccanti nel tardo pomeriggio di ieri con l&#8217;accoglienza del simulacro in zona Montagnano e la successiva consegna nelle mani del Parroco Don Gerardo Petruccelli in Piazza A. Ricca da parte del Comandante della Compagnia Carabinieri di Venosa, Capitano Marco Capasso e del personale della Stazione Carabinieri di Genzano di Lucania, davanti a una folla visibilmente emozionata ed alla presenza del Comandante del Nucleo Operativo e Radiomobile della Compagnia Carabinieri di Formia, Capitano Antonio Sarno e del personale della locale Stazione. Quindi la Messa presieduta dall&#8217;Arcivescovo di Gaeta, S.E. Mons. Luigi Vari e la successiva inaugurazione della mostra storica \u201cI Bambinelli Maranolesi\u201d presso la Chiesa di Sant&#8217;Antonio.<\/p>\n<div id=\"radio-1369134447\" class=\"radio-dopo-il-contenuto radio-entity-placement\"><a href=\"https:\/\/concessionari-suzuki.it\/bodema\/\" aria-label=\"Bodema 1200&#215;600 banner Suzuki_AX\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2025\/05\/Bodema-1200x600-banner-Suzuki_AX.jpg\" alt=\"\"  srcset=\"https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2025\/05\/Bodema-1200x600-banner-Suzuki_AX.jpg 1200w, https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2025\/05\/Bodema-1200x600-banner-Suzuki_AX-768x384.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" width=\"800\" height=\"300\"   \/><\/a><\/div>","protected":false},"excerpt":{"rendered":"<p>FORMIA &#8211; A undici anni dalla sua sparizione a seguito di un furto, \u00e8 tornato nel pomeriggio di ieri alla comunit\u00e0 di Maranola il Bambinello di Sant&#8217;Antonio, uno dei simboli religiosi e culturali pi\u00f9 amati. La scultura lignea policroma risalente alla fine del XVIII secolo era stata rubata a maggio del 2015. Sono stati i [&hellip;]<\/p>\n","protected":false},"author":62,"featured_media":430127,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[7],"tags":[5738],"class_list":["post-430126","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cronaca","tag-in-primo-piano"],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/430126","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/users\/62"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/comments?post=430126"}],"version-history":[{"count":1,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/430126\/revisions"}],"predecessor-version":[{"id":430129,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/430126\/revisions\/430129"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/media\/430127"}],"wp:attachment":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/media?parent=430126"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/categories?post=430126"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/tags?post=430126"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}