{"id":433450,"date":"2026-07-14T14:38:11","date_gmt":"2026-07-14T12:38:11","guid":{"rendered":"https:\/\/www.radioluna.it\/news\/?p=433450"},"modified":"2026-07-14T14:38:33","modified_gmt":"2026-07-14T12:38:33","slug":"v","status":"publish","type":"post","link":"https:\/\/www.radioluna.it\/news\/2026\/07\/v\/","title":{"rendered":"Terracina: aggredi\u2019 la compagna davanti ai figli, arrestato"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p>Aggred\u00ec la compagna davanti gli occhi dei figli ora finisce in manette. Ieri pomeriggio i Carabinieri di Priverno hanno arrestato un uomo di 65 anni di Terracina in esecuzione di un ordine di carcerazione emesso dalla Procura Generale della Repubblica presso la Corte d&#8217;Appello di Roma.\u00a0 Il provvedimento restrittivo \u00e8 stato emesso a seguito della sentenza di condanna passata in giudicato a 2 anni e mesi 8 per maltrattamenti in famiglia. Per lo stesso motivo, l\u2019uomo era gi\u00e0 sottoposto agli arresti domiciliari, con applicazione del braccialetto elettronico, a partire dall&#8217;agosto 2024.\u00a0 I fatti risalgono al luglio 2024, quando il 65enne aggred\u00ec fisicamente la compagna convivente, minacciandola anche di morte, alla presenza dei figli minori.\u00a0 Al termine delle formalit\u00e0 di rito, l&#8217;uomo \u00e8 stato condotto presso la Casa Circondariale di Latina.<\/p>\n<div id=\"radio-3057768750\" class=\"radio-dopo-il-contenuto radio-entity-placement\"><a href=\"https:\/\/concessionari-suzuki.it\/bodema\/\" aria-label=\"Bodema 1200&#215;600 banner Suzuki_AX\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2025\/05\/Bodema-1200x600-banner-Suzuki_AX.jpg\" alt=\"\"  srcset=\"https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2025\/05\/Bodema-1200x600-banner-Suzuki_AX.jpg 1200w, https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2025\/05\/Bodema-1200x600-banner-Suzuki_AX-768x384.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" width=\"800\" height=\"300\"   \/><\/a><\/div>","protected":false},"excerpt":{"rendered":"<p>Aggred\u00ec la compagna davanti gli occhi dei figli ora finisce in manette. Ieri pomeriggio i Carabinieri di Priverno hanno arrestato un uomo di 65 anni di Terracina in esecuzione di un ordine di carcerazione emesso dalla Procura Generale della Repubblica presso la Corte d&#8217;Appello di Roma.\u00a0 Il provvedimento restrittivo \u00e8 stato emesso a seguito della [&hellip;]<\/p>\n","protected":false},"author":5444,"featured_media":375964,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[2256,2428],"tags":[5738],"class_list":["post-433450","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-prima-pagina","category-primo-piano","tag-in-primo-piano"],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/433450","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/users\/5444"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/comments?post=433450"}],"version-history":[{"count":2,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/433450\/revisions"}],"predecessor-version":[{"id":433452,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/433450\/revisions\/433452"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/media\/375964"}],"wp:attachment":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/media?parent=433450"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/categories?post=433450"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/tags?post=433450"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}