{"id":433519,"date":"2026-07-15T17:09:18","date_gmt":"2026-07-15T15:09:18","guid":{"rendered":"https:\/\/www.radioluna.it\/news\/?p=433519"},"modified":"2026-07-15T17:09:18","modified_gmt":"2026-07-15T15:09:18","slug":"furto-ai-danni-di-unanziana-a-gaeta-arrestati-quattro-cittadini-stranieri-sulla-pontina","status":"publish","type":"post","link":"https:\/\/www.radioluna.it\/news\/2026\/07\/furto-ai-danni-di-unanziana-a-gaeta-arrestati-quattro-cittadini-stranieri-sulla-pontina\/","title":{"rendered":"Furto ai danni di un&#8217;anziana a Gaeta, arrestati quattro cittadini stranieri sulla Pontina"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p style=\"text-align: justify;\" data-start=\"113\" data-end=\"335\">La Polizia di Stato ha arrestato quattro cittadini stranieri, tre di nazionalit\u00e0 cubana e uno peruviana, ritenuti gravemente indiziati dei reati di furto aggravato in concorso e indebito utilizzo di strumenti di pagamento. L&#8217;intervento \u00e8 scattato dopo un furto ai danni di un&#8217;anziana donna avvenuto nel territorio di Gaeta. Il veicolo utilizzato dai presunti autori del reato \u00e8 stato segnalato agli operatori e successivamente intercettato lungo la Strada Regionale 148 Pontina dagli agenti della Squadra Volante della Questura di Latina, con la collaborazione dei Commissariati di Cisterna di Latina e Gaeta. L&#8217;autovettura \u00e8 stata individuata nei pressi dell&#8217;area di servizio &#8220;Autogrill Latina Pontina&#8221;. Gli occupanti sono stati controllati e accompagnati negli uffici della Questura per gli accertamenti di rito.<\/p>\n<p style=\"text-align: justify;\" data-start=\"931\" data-end=\"1154\">Le successive verifiche, anche attraverso l&#8217;analisi delle immagini di videosorveglianza e il riconoscimento della refurtiva da parte della vittima, avrebbero consentito di raccogliere elementi a carico dei quattro indagati. Durante le perquisizioni personali e del veicolo sono stati recuperati parte degli oggetti sottratti alla donna e denaro ritenuto provento dell&#8217;attivit\u00e0 illecita. Secondo la ricostruzione degli investigatori, il gruppo avrebbe agito con una tecnica organizzata: alcuni componenti avrebbero distratto la vittima mentre un complice si impossessava della borsa contenente effetti personali, denaro e carte di pagamento.\u00a0L&#8217;auto utilizzata, presa a noleggio pochi giorni prima dei fatti, \u00e8 stata sequestrata. I quattro arrestati sono stati messi a disposizione dell&#8217;autorit\u00e0 giudiziaria in attesa dell&#8217;udienza di convalida. Dagli accertamenti \u00e8 inoltre emerso che gli arrestati risultano gravati da numerosi precedenti di polizia, in particolare per reati contro il patrimonio.<\/p>\n<div id=\"radio-683147790\" class=\"radio-dopo-il-contenuto radio-entity-placement\"><a href=\"https:\/\/concessionari-suzuki.it\/bodema\/\" aria-label=\"Bodema 1200&#215;600 banner Suzuki_AX\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2025\/05\/Bodema-1200x600-banner-Suzuki_AX.jpg\" alt=\"\"  srcset=\"https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2025\/05\/Bodema-1200x600-banner-Suzuki_AX.jpg 1200w, https:\/\/www.radioluna.it\/news\/wp-content\/uploads\/2025\/05\/Bodema-1200x600-banner-Suzuki_AX-768x384.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" width=\"800\" height=\"300\"   \/><\/a><\/div>","protected":false},"excerpt":{"rendered":"<p>La Polizia di Stato ha arrestato quattro cittadini stranieri, tre di nazionalit\u00e0 cubana e uno peruviana, ritenuti gravemente indiziati dei reati di furto aggravato in concorso e indebito utilizzo di strumenti di pagamento. L&#8217;intervento \u00e8 scattato dopo un furto ai danni di un&#8217;anziana donna avvenuto nel territorio di Gaeta. Il veicolo utilizzato dai presunti autori [&hellip;]<\/p>\n","protected":false},"author":5443,"featured_media":433520,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[7,2256,2428],"tags":[5738],"class_list":["post-433519","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cronaca","category-prima-pagina","category-primo-piano","tag-in-primo-piano"],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/433519","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/users\/5443"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/comments?post=433519"}],"version-history":[{"count":1,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/433519\/revisions"}],"predecessor-version":[{"id":433521,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/posts\/433519\/revisions\/433521"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/media\/433520"}],"wp:attachment":[{"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/media?parent=433519"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/categories?post=433519"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radioluna.it\/news\/wp-json\/wp\/v2\/tags?post=433519"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}